{"id":13877,"date":"2025-03-26T11:27:47","date_gmt":"2025-03-26T11:27:47","guid":{"rendered":"https:\/\/legendnilecruise.com\/?p=13877"},"modified":"2025-03-26T11:28:09","modified_gmt":"2025-03-26T11:28:09","slug":"gods-of-egypt-ll","status":"publish","type":"post","link":"https:\/\/legendnilecruise.com\/de\/gotter-des-alten-agyptens\/gotter-agyptens-ll\/","title":{"rendered":"G\u00f6tter von \u00c4gypten II"},"content":{"rendered":"<p>Pantheon der Macht: Die Gottheiten des alten \u00c4gypten<\/p>\n<p><img fetchpriority=\"high\" decoding=\"async\" class=\"wp-image-13878 aligncenter\" src=\"https:\/\/legendnilecruise.com\/wp-content\/uploads\/2025\/03\/Gods-Of-Egypt-ll-300x169.jpg\" alt=\"\" width=\"415\" height=\"234\" srcset=\"https:\/\/legendnilecruise.com\/wp-content\/uploads\/2025\/03\/Gods-Of-Egypt-ll-300x169.jpg 300w, https:\/\/legendnilecruise.com\/wp-content\/uploads\/2025\/03\/Gods-Of-Egypt-ll.jpg 612w\" sizes=\"(max-width: 415px) 100vw, 415px\" \/><\/p>\n<h3 style=\"text-align: center;\"><strong>Der Gott Ra<\/strong><\/h3>\n<p style=\"text-align: center;\">Der Gott Ra gilt als einer der wichtigsten alt\u00e4gyptischen G\u00f6tter. Nach dem alt\u00e4gyptischen Glauben der Ashmunin-Doktrin glaubten sie, dass das Universum aus einem kosmischen Ei oder einer Lotusblume geschaffen wurde. Das kosmische Ei stammte von dem Ibisvogel (Thoth) und aus ihm ging die Gottheit Ra (der Sonnengott) hervor. Aus der Lotosblume ging der Gott Ra in zwei Formen hervor, entweder als Skarab\u00e4us (Khepri) oder als kleines Kind (Nefertem). Die alten \u00c4gypter betrachteten die Sonne als eine der wichtigsten Quellen kosmischer Energie, denn die Sonne geht jeden Morgen auf und abends unter. Die alten \u00c4gypter gaben der Sonne drei Namen: Ra, Khepri und Atum. Ra nahm drei Formen an: Am Mittag nahm er die Form von Ra als Sonnenscheibe an. Am Morgen nahm er die Gestalt von Khepri (dem Skarab\u00e4us) an. Bei Sonnenuntergang nahm er die Gestalt von Atum an, einem alten Mann, der einen Stock h\u00e4lt. Der Gott Ra wurde entweder als Sonnenscheibe oder mit einem Falkenkopf und einer Sonnenscheibe auf dem Kopf, umgeben von einer Schlange, dargestellt. Er wurde seit Beginn der \u00e4gyptischen Geschichte verehrt, und in ganz \u00c4gypten wurden Tempel f\u00fcr ihn gebaut. Seine t\u00e4gliche Reise \u00fcber den Himmel von Sonnenaufgang bis Sonnenuntergang stellte den Zyklus von Leben, Wiedergeburt und Tod dar, w\u00e4hrend seine n\u00e4chtliche Reise durch die Unterwelt die Erneuerung der Sonne an jedem Morgen symbolisierte. Ra repr\u00e4sentierte nicht nur die lebensspendende Energie der Sonne, sondern verk\u00f6rperte auch die Prinzipien der Sch\u00f6pfung und der ewigen Erneuerung.<\/p>\n<p><img decoding=\"async\" class=\"wp-image-13904 aligncenter\" src=\"https:\/\/legendnilecruise.com\/wp-content\/uploads\/2025\/03\/Gods-Of-Egypt-ll-211x300.png\" alt=\"\" width=\"341\" height=\"485\" srcset=\"https:\/\/legendnilecruise.com\/wp-content\/uploads\/2025\/03\/Gods-Of-Egypt-ll-211x300.png 211w, https:\/\/legendnilecruise.com\/wp-content\/uploads\/2025\/03\/Gods-Of-Egypt-ll-719x1024.png 719w, https:\/\/legendnilecruise.com\/wp-content\/uploads\/2025\/03\/Gods-Of-Egypt-ll-768x1093.png 768w, https:\/\/legendnilecruise.com\/wp-content\/uploads\/2025\/03\/Gods-Of-Egypt-ll-316x450.png 316w, https:\/\/legendnilecruise.com\/wp-content\/uploads\/2025\/03\/Gods-Of-Egypt-ll.png 902w\" sizes=\"(max-width: 341px) 100vw, 341px\" \/><\/p>\n<p style=\"text-align: center;\">Der Gott Ra mit dem Kopf eines Falken, der von einer Sonnenscheibe \u00fcberragt wird<\/p>\n<h3 style=\"text-align: center;\"><strong>Der Gott Ptah<\/strong><\/h3>\n<p style=\"text-align: center;\">Im alt\u00e4gyptischen Glauben war der Gott Ptah in der Theologie der Memphiten der Sch\u00f6pfergott. Seine Funktion war die Sch\u00f6pfung durch das Wort, und das Wort kam immer aus dem Herzen, bevor es die Zunge erreichte. Der Gott Ptah galt als einer der wichtigsten alt\u00e4gyptischen G\u00f6tter w\u00e4hrend der gesamten Geschichte der alt\u00e4gyptischen Zivilisation, sogar bis in die griechische und r\u00f6mische Zeit. Der Gott Ptah galt auch als Gott der K\u00fcnste, des Handwerks und der Industrie. Er war mit dem Gott der Toten in Saqqara (dem Gott Sokar) verbunden, so dass sein Name in Saqqara zu \"Ptah-Sokar\" wurde und er als Totengott galt. Er bildete eine Triade, die aus ihm selbst, seiner Frau, der G\u00f6ttin Sekhmet (einer Kriegsg\u00f6ttin, die oft als L\u00f6win dargestellt wurde), und ihrem Sohn Nefertem bestand, der immer als Kind dargestellt wurde, das aus einer Lotusbl\u00fcte hervorkam. Ptah wurde als Mensch dargestellt, der einen Kopfschmuck mit einer Amun-Krone tr\u00e4gt und einen Stock aus Holz oder Stein h\u00e4lt.<\/p>\n<p><img decoding=\"async\" class=\"wp-image-13905 aligncenter\" src=\"https:\/\/legendnilecruise.com\/wp-content\/uploads\/2025\/03\/Gods-Of-Egypt-ll-2-300x176.png\" alt=\"\" width=\"413\" height=\"242\" srcset=\"https:\/\/legendnilecruise.com\/wp-content\/uploads\/2025\/03\/Gods-Of-Egypt-ll-2-300x176.png 300w, https:\/\/legendnilecruise.com\/wp-content\/uploads\/2025\/03\/Gods-Of-Egypt-ll-2-768x451.png 768w, https:\/\/legendnilecruise.com\/wp-content\/uploads\/2025\/03\/Gods-Of-Egypt-ll-2-767x450.png 767w, https:\/\/legendnilecruise.com\/wp-content\/uploads\/2025\/03\/Gods-Of-Egypt-ll-2.png 927w\" sizes=\"(max-width: 413px) 100vw, 413px\" \/><\/p>\n<p style=\"text-align: center;\">(Statue des Gottes Ptah - \u00c4gyptisches Museum in Turin, Italien<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-13906 aligncenter\" src=\"https:\/\/legendnilecruise.com\/wp-content\/uploads\/2025\/03\/Gods-Of-Egypt-ll-3-174x300.png\" alt=\"\" width=\"290\" height=\"500\" srcset=\"https:\/\/legendnilecruise.com\/wp-content\/uploads\/2025\/03\/Gods-Of-Egypt-ll-3-174x300.png 174w, https:\/\/legendnilecruise.com\/wp-content\/uploads\/2025\/03\/Gods-Of-Egypt-ll-3.png 321w\" sizes=\"(max-width: 290px) 100vw, 290px\" \/><\/p>\n<p style=\"text-align: center;\">Eine der Formen der Gottheit Ptah, die ein Gewand tr\u00e4gt und das Zepter h\u00e4lt<\/p>\n<h3 style=\"text-align: center;\"><strong>Der Gott Aten<\/strong><\/h3>\n<p style=\"text-align: center;\">Die Verehrung des Gottes Aten kam w\u00e4hrend der Herrschaft von K\u00f6nig Echnaton aus der achtzehnten Dynastie auf. Echnaton war ein K\u00f6nig, Dichter und sensibler Mensch, der eher als Philosoph denn als Herrscher galt. Er forderte die Verehrung des Gottes Aten als einzigem Gott des Staates. Diese Idee war in der alt\u00e4gyptischen Denkweise, die an die Existenz einer Gruppe von G\u00f6ttern gew\u00f6hnt war, nicht \u00fcblich. Die Priester des Amun-Ra in Theben lehnten diese Idee ab. Echnaton beschloss, einen neuen Ort aufzusuchen, um mit seiner sch\u00f6nen Frau Nofretete und ihren Kindern seinen neuen Gott Aten zu verehren. Aten ist der Sonnengott, aber in Echnatons Denken ist er nicht nur der Sonnengott, sondern auch das Zentrum der Wahrheit und Ehrlichkeit. Er wurde als eine Sonnenscheibe dargestellt, deren Strahlen in menschlichen H\u00e4nden enden. Echnatons Kunst zeichnete sich durch den Ausdruck der Wahrheit aus. Echnaton stellte sich selbst in einer Weise dar, die das Bild eines kranken Mannes mit dem eines mitf\u00fchlenden und liebevollen Menschen mit seiner Frau und seinen Kindern verband. und \u00e4nderte die \u00fcbliche Form der K\u00f6nige, die sich auf einen Idealismus in der Darstellung st\u00fctzte, der die Schw\u00e4chen des Einzelnen verbarg. Er errichtete eine komplette Stadt f\u00fcr die Verehrung des Gottes Aten, die er Akhet-Aten nannte, was \"Horizont des Aten\" bedeutet, und machte sie zu seiner Hauptstadt, um dort mit seiner sch\u00f6nen Frau Nofretete und ihren Kindern zu verehren. K\u00f6nig Echnaton wurde an den W\u00e4nden der Gem\u00e4cher abgebildet, und am Rande der Stadt (Tell el-Amarna, heute im Gouvernement Minya) wurden Wandmalereien gefunden. Es ist bemerkenswert, dass zum ersten Mal in der alt\u00e4gyptischen Geschichte ein Gott nicht in einer Triade auftrat, was auf seine Einzigartigkeit hinweist. Er betrachtete Aten als den einen und einzigen Gott. Die Verehrung des Gottes Aten wurde nach Echnaton nicht fortgesetzt. Selbst sein Sohn Tutanchamun \u00e4nderte seinen Namen von Tutankhaten in Tutanchamun und kehrte zur Verehrung des Gottes Amun-Ra in Theben zur\u00fcck.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-13907 aligncenter\" src=\"https:\/\/legendnilecruise.com\/wp-content\/uploads\/2025\/03\/Gods-Of-Egypt-ll-3-300x236.jpg\" alt=\"\" width=\"390\" height=\"307\" srcset=\"https:\/\/legendnilecruise.com\/wp-content\/uploads\/2025\/03\/Gods-Of-Egypt-ll-3-300x236.jpg 300w, https:\/\/legendnilecruise.com\/wp-content\/uploads\/2025\/03\/Gods-Of-Egypt-ll-3.jpg 565w\" sizes=\"(max-width: 390px) 100vw, 390px\" \/><\/p>\n<p style=\"text-align: center;\">Der Gott Aten erscheint in Form einer Sonnenscheibe, aus der Strahlen austreten, die in menschlichen H\u00e4nden enden<\/p>\n<h3 style=\"text-align: center;\"><strong>Der Gott Anubis<\/strong><\/h3>\n<p style=\"text-align: center;\">Sein Name bedeutet \"der k\u00f6nigliche Sohn\", denn der Mythos besagt, dass die G\u00f6ttin Nephthys ihn heimlich von ihrem Bruder Osiris zur Welt brachte. Aus Angst vor ihrem Ehemann Set setzte sie ihn in den S\u00fcmpfen aus. Anubis wurde heimlich von den G\u00f6ttinnen Nephthys und Isis aufgezogen. Als Anubis erwachsen wurde, beteiligte er sich mit Isis und Nephthys an der Mumifizierung des Gottes Osiris. Aus diesem Grund wurde Anubis mit Friedh\u00f6fen und den Toten in Verbindung gebracht. Anubis wurde als Schakal oder als Hund mit dem Kopf eines Schakals abgebildet. Er wurde immer in Schwarz dargestellt, manchmal auch als Mensch mit Schakalkopf. Eine der wichtigsten Aufgaben von Anubis war die Bewachung von K\u00f6nigsgr\u00e4bern. Nach dem Tod eines Menschen nahm Anubis daran teil, das Herz des Verstorbenen vor dem Gott Osiris zu wiegen, was als Totengericht oder Osirisches Gericht bekannt ist.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-13909 aligncenter\" src=\"https:\/\/legendnilecruise.com\/wp-content\/uploads\/2025\/03\/Gods-Of-Egypt-ll-4-300x184.png\" alt=\"\" width=\"400\" height=\"245\" srcset=\"https:\/\/legendnilecruise.com\/wp-content\/uploads\/2025\/03\/Gods-Of-Egypt-ll-4-300x184.png 300w, https:\/\/legendnilecruise.com\/wp-content\/uploads\/2025\/03\/Gods-Of-Egypt-ll-4-768x471.png 768w, https:\/\/legendnilecruise.com\/wp-content\/uploads\/2025\/03\/Gods-Of-Egypt-ll-4-734x450.png 734w, https:\/\/legendnilecruise.com\/wp-content\/uploads\/2025\/03\/Gods-Of-Egypt-ll-4.png 975w\" sizes=\"(max-width: 400px) 100vw, 400px\" \/><\/p>\n<p style=\"text-align: center;\">Eine Ansicht des Gottes Anubis aus dem Grab der Nefertari, die ihn beim Laufen in der Gruft zeigt<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-13910 aligncenter\" src=\"https:\/\/legendnilecruise.com\/wp-content\/uploads\/2025\/03\/Gods-Of-Egypt-ll-5-300x184.png\" alt=\"\" width=\"398\" height=\"244\" srcset=\"https:\/\/legendnilecruise.com\/wp-content\/uploads\/2025\/03\/Gods-Of-Egypt-ll-5-300x184.png 300w, https:\/\/legendnilecruise.com\/wp-content\/uploads\/2025\/03\/Gods-Of-Egypt-ll-5-768x470.png 768w, https:\/\/legendnilecruise.com\/wp-content\/uploads\/2025\/03\/Gods-Of-Egypt-ll-5-735x450.png 735w, https:\/\/legendnilecruise.com\/wp-content\/uploads\/2025\/03\/Gods-Of-Egypt-ll-5.png 943w\" sizes=\"(max-width: 398px) 100vw, 398px\" \/><\/p>\n<p style=\"text-align: center;\">Gott Anubis, dargestellt beim Ritual des \u00d6ffnens des Mundes des Verstorbenen aus dem Buch der Toten<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-13912 aligncenter\" src=\"https:\/\/legendnilecruise.com\/wp-content\/uploads\/2025\/03\/Gods-Of-Egypt-ll-6-300x160.png\" alt=\"\" width=\"431\" height=\"230\" srcset=\"https:\/\/legendnilecruise.com\/wp-content\/uploads\/2025\/03\/Gods-Of-Egypt-ll-6-300x160.png 300w, https:\/\/legendnilecruise.com\/wp-content\/uploads\/2025\/03\/Gods-Of-Egypt-ll-6-768x409.png 768w, https:\/\/legendnilecruise.com\/wp-content\/uploads\/2025\/03\/Gods-Of-Egypt-ll-6-846x450.png 846w, https:\/\/legendnilecruise.com\/wp-content\/uploads\/2025\/03\/Gods-Of-Egypt-ll-6.png 934w\" sizes=\"(max-width: 431px) 100vw, 431px\" \/><\/p>\n<p style=\"text-align: center;\">Eine Szene, die den Gott Anubis im Hof des Osiris darstellt<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-13913 aligncenter\" src=\"https:\/\/legendnilecruise.com\/wp-content\/uploads\/2025\/03\/Gods-Of-Egypt-ll-7-300x184.png\" alt=\"\" width=\"439\" height=\"269\" srcset=\"https:\/\/legendnilecruise.com\/wp-content\/uploads\/2025\/03\/Gods-Of-Egypt-ll-7-300x184.png 300w, https:\/\/legendnilecruise.com\/wp-content\/uploads\/2025\/03\/Gods-Of-Egypt-ll-7-768x471.png 768w, https:\/\/legendnilecruise.com\/wp-content\/uploads\/2025\/03\/Gods-Of-Egypt-ll-7.png 927w, https:\/\/legendnilecruise.com\/wp-content\/uploads\/2025\/03\/Gods-Of-Egypt-ll-7-734x450.png 734w\" sizes=\"(max-width: 439px) 100vw, 439px\" \/><\/p>\n<p style=\"text-align: center;\">(Statue des Anubis aus dem Grab des Tutanchamun)<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-13918 aligncenter\" src=\"https:\/\/legendnilecruise.com\/wp-content\/uploads\/2025\/03\/Gods-Of-Egypt-ll-8-300x149.png\" alt=\"\" width=\"459\" height=\"228\" srcset=\"https:\/\/legendnilecruise.com\/wp-content\/uploads\/2025\/03\/Gods-Of-Egypt-ll-8-300x149.png 300w, https:\/\/legendnilecruise.com\/wp-content\/uploads\/2025\/03\/Gods-Of-Egypt-ll-8-768x382.png 768w, https:\/\/legendnilecruise.com\/wp-content\/uploads\/2025\/03\/Gods-Of-Egypt-ll-8.png 878w\" sizes=\"(max-width: 459px) 100vw, 459px\" \/><\/p>\n<p style=\"text-align: center;\">((Eine Statue des Anubis aus der Sp\u00e4tzeit ist im Kopenhagener Museum in D\u00e4nemark ausgestellt<\/p>\n<h3 style=\"text-align: center;\"><strong>Die G\u00f6ttin Bastet<\/strong><\/h3>\n<p style=\"text-align: center;\">Bastet nahm die Gestalt einer Katze oder einer Frau mit dem Kopf einer Katze an. Die alten \u00c4gypter lagerten Getreide, insbesondere Weizen und Gerste, in ihrem Haus, aber Ratten w\u00fcrden das Getreide verderben. Deshalb zogen die alten \u00c4gypter Katzen im Haus auf, um die Ratten zu jagen, und aus diesem Grund liebten sie sie sehr und zogen sie im Haus auf. Wenn eine Katze starb, begruben die alten \u00c4gypter sie zun\u00e4chst mit ihnen in ihren Gr\u00e4bern, sp\u00e4ter aber in speziellen Gr\u00e4bern, die als die Gr\u00e4ber von Bastets Katze bekannt waren, und sie wurde mumifiziert. Katzen spielten mit Kindern, und aus diesem Grund betrachteten sie sie als Gl\u00fccksg\u00f6ttin, wie der Gott Bes. Die alten \u00c4gypter gr\u00fcndeten ihr zu Ehren eine Stadt und nannten sie Bubastis, die heute im Gouvernement Sharqiya liegt. Die alten \u00c4gypter feierten ein Fest f\u00fcr sie, und ihr Fest war das Fest des Gl\u00fccks, und aus diesem Grund war es das \u00e4gyptischste Fest, bei dem Wein getrunken wurde.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-13919 aligncenter\" src=\"https:\/\/legendnilecruise.com\/wp-content\/uploads\/2025\/03\/Gods-Of-Egypt-ll-8-300x147.jpg\" alt=\"\" width=\"435\" height=\"213\" srcset=\"https:\/\/legendnilecruise.com\/wp-content\/uploads\/2025\/03\/Gods-Of-Egypt-ll-8-300x147.jpg 300w, https:\/\/legendnilecruise.com\/wp-content\/uploads\/2025\/03\/Gods-Of-Egypt-ll-8.jpg 578w\" sizes=\"(max-width: 435px) 100vw, 435px\" \/><\/p>\n<p style=\"text-align: center;\">Statue von Bastet im Louvre-Museum, Paris<\/p>\n<h3 style=\"text-align: center;\"><strong>Der Gott Sobek<\/strong><\/h3>\n<p style=\"text-align: center;\">Der Nil spielte zusammen mit der Sonne die wichtigste Rolle im Leben der alten \u00c4gypter. Der Nil brachte Wasser und Nahrung, sei es durch Fischfang oder durch die Nutzung des Wassers f\u00fcr die Landwirtschaft. Die alten \u00c4gypter f\u00fcrchteten das Krokodil, weil es das einzige Tier war, das ihnen auf ihren Reisen zwischen den St\u00e4dten den Weg versperren konnte, denn sie waren auf den Nil als Transportmittel angewiesen. Die alten \u00c4gypter verehrten das Krokodil und nannten es den Gott Sobek (den Krokodilgott). Er wurde in einer Reihe von Regionen verehrt, vor allem in Fayoum und Kom Ombo. Der Gott Sobek wurde immer in Form eines Krokodils oder eines Mannes mit einem Krokodilkopf abgebildet.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-13920 aligncenter\" src=\"https:\/\/legendnilecruise.com\/wp-content\/uploads\/2025\/03\/Gods-Of-Egypt-ll-9-275x300.png\" alt=\"\" width=\"389\" height=\"424\" srcset=\"https:\/\/legendnilecruise.com\/wp-content\/uploads\/2025\/03\/Gods-Of-Egypt-ll-9-275x300.png 275w, https:\/\/legendnilecruise.com\/wp-content\/uploads\/2025\/03\/Gods-Of-Egypt-ll-9-412x450.png 412w, https:\/\/legendnilecruise.com\/wp-content\/uploads\/2025\/03\/Gods-Of-Egypt-ll-9.png 653w\" sizes=\"(max-width: 389px) 100vw, 389px\" \/><\/p>\n<p style=\"text-align: center;\">Statue von Sobek mit Amenhotep III - Luxor Museum f\u00fcr alt\u00e4gyptische Kunst<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-13921 aligncenter\" src=\"https:\/\/legendnilecruise.com\/wp-content\/uploads\/2025\/03\/Gods-Of-Egypt-ll-10-138x300.png\" alt=\"\" width=\"234\" height=\"508\" srcset=\"https:\/\/legendnilecruise.com\/wp-content\/uploads\/2025\/03\/Gods-Of-Egypt-ll-10-138x300.png 138w, https:\/\/legendnilecruise.com\/wp-content\/uploads\/2025\/03\/Gods-Of-Egypt-ll-10-207x450.png 207w, https:\/\/legendnilecruise.com\/wp-content\/uploads\/2025\/03\/Gods-Of-Egypt-ll-10.png 312w\" sizes=\"(max-width: 234px) 100vw, 234px\" \/><\/p>\n<p style=\"text-align: center;\">Eine Ansicht, die das Aussehen des Idols Sobek mit dem Kopf eines Krokodils zeigt<\/p>\n<h3 style=\"text-align: center;\"><strong>Der Gott Hapi<\/strong><\/h3>\n<p style=\"text-align: center;\">Hapi ist der Gott des Nils. Sein Name \"Hapi\" bedeutet \"der Gl\u00fcckliche\" oder \"Gl\u00fcck\". Der Gott Hapi ist einer der S\u00f6hne des Gottes Horus und wird immer als Mann mit einer weiblichen Figur unter seinem Arm dargestellt. F\u00fcr die alten \u00c4gypter wurde der Nil als Mann dargestellt, der die Flut bringt, die die Fruchtbarkeit symbolisiert, w\u00e4hrend die weibliche Figur die Frau symbolisiert, die ihr Kind stillt. Die Verehrung des Gottes Hapi war im alten \u00c4gypten im ganzen Land bekannt. Auf dem K\u00f6nigsthron wurde Hapi immer auf beiden Seiten dargestellt, und zwar beim so genannten Sed-Fest (der Vereinigung der beiden L\u00e4nder, d. h. des Nordens und des S\u00fcdens). Er wurde gezeichnet, indem er die Symbole der \u00e4gyptischen Bauern, Papyrus und Lotus, in einer S\u00e4ule verband, die vom Herzen ausging. Das Herz bezieht sich auf das \u00e4gyptische Land und die S\u00e4ule auf den Nil. Die Feste des Gottes Hapi wurden mit der Flut in Verbindung gebracht. Ihm wurden Opfergaben dargebracht, um die Flut zu feiern, die \u00c4gypten seine G\u00fcte und Sicherheit gab. In einigen Szenen wird er in den Heiligt\u00fcmern dargestellt, w\u00e4hrend er die reichhaltigen G\u00fcter \u00c4gyptens tr\u00e4gt und sie dem K\u00f6nig und den G\u00f6ttern darbringt. Der Gott Hapi wurde im Allerheiligsten abgebildet. Es gibt 42 Szenen, in denen Hapi Opfergaben darbringt, was sich auf die 42 \u00e4gyptischen Provinzen bezieht.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-13922 aligncenter\" src=\"https:\/\/legendnilecruise.com\/wp-content\/uploads\/2025\/03\/Gods-Of-Egypt-ll-10-300x183.jpg\" alt=\"\" width=\"459\" height=\"280\" srcset=\"https:\/\/legendnilecruise.com\/wp-content\/uploads\/2025\/03\/Gods-Of-Egypt-ll-10-300x183.jpg 300w, https:\/\/legendnilecruise.com\/wp-content\/uploads\/2025\/03\/Gods-Of-Egypt-ll-10-1024x626.jpg 1024w, https:\/\/legendnilecruise.com\/wp-content\/uploads\/2025\/03\/Gods-Of-Egypt-ll-10-768x470.jpg 768w, https:\/\/legendnilecruise.com\/wp-content\/uploads\/2025\/03\/Gods-Of-Egypt-ll-10-736x450.jpg 736w, https:\/\/legendnilecruise.com\/wp-content\/uploads\/2025\/03\/Gods-Of-Egypt-ll-10.jpg 1207w\" sizes=\"(max-width: 459px) 100vw, 459px\" \/><\/p>\n<p style=\"text-align: center;\">Eine Szene, die den Gott Hapi auf dem Thron zeigt<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-13923 aligncenter\" src=\"https:\/\/legendnilecruise.com\/wp-content\/uploads\/2025\/03\/Gods-Of-Egypt-ll-11-300x232.jpg\" alt=\"\" width=\"426\" height=\"329\" srcset=\"https:\/\/legendnilecruise.com\/wp-content\/uploads\/2025\/03\/Gods-Of-Egypt-ll-11-300x232.jpg 300w, https:\/\/legendnilecruise.com\/wp-content\/uploads\/2025\/03\/Gods-Of-Egypt-ll-11-1024x792.jpg 1024w, https:\/\/legendnilecruise.com\/wp-content\/uploads\/2025\/03\/Gods-Of-Egypt-ll-11-768x594.jpg 768w, https:\/\/legendnilecruise.com\/wp-content\/uploads\/2025\/03\/Gods-Of-Egypt-ll-11-582x450.jpg 582w, https:\/\/legendnilecruise.com\/wp-content\/uploads\/2025\/03\/Gods-Of-Egypt-ll-11.jpg 1238w\" sizes=\"(max-width: 426px) 100vw, 426px\" \/><\/p>\n<p style=\"text-align: center;\">Der obere Teil der Statue des Gottes Hapi ist in Berlin ausgestellt<\/p>","protected":false},"excerpt":{"rendered":"<p>Pantheon der Macht: Die Gottheiten des alten \u00c4gypten Der Gott Ra Der Gott Ra gilt als einer der wichtigsten alt\u00e4gyptischen G\u00f6tter. Im alt\u00e4gyptischen Glauben der Ashmunin-Doktrin glaubten sie, dass das Universum aus einem kosmischen Ei oder einer Lotusblume erschaffen wurde. Das kosmische Ei stammte von dem Ibis-Vogel [...]<\/p>","protected":false},"author":1,"featured_media":13878,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[75],"tags":[],"class_list":["post-13877","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-gods-of-ancient-egypt"],"_links":{"self":[{"href":"https:\/\/legendnilecruise.com\/de\/wp-json\/wp\/v2\/posts\/13877","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/legendnilecruise.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/legendnilecruise.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/legendnilecruise.com\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/legendnilecruise.com\/de\/wp-json\/wp\/v2\/comments?post=13877"}],"version-history":[{"count":4,"href":"https:\/\/legendnilecruise.com\/de\/wp-json\/wp\/v2\/posts\/13877\/revisions"}],"predecessor-version":[{"id":13927,"href":"https:\/\/legendnilecruise.com\/de\/wp-json\/wp\/v2\/posts\/13877\/revisions\/13927"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/legendnilecruise.com\/de\/wp-json\/wp\/v2\/media\/13878"}],"wp:attachment":[{"href":"https:\/\/legendnilecruise.com\/de\/wp-json\/wp\/v2\/media?parent=13877"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/legendnilecruise.com\/de\/wp-json\/wp\/v2\/categories?post=13877"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/legendnilecruise.com\/de\/wp-json\/wp\/v2\/tags?post=13877"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}