{"id":13803,"date":"2025-03-26T11:06:50","date_gmt":"2025-03-26T11:06:50","guid":{"rendered":"https:\/\/legendnilecruise.com\/?p=13803"},"modified":"2025-03-26T11:08:12","modified_gmt":"2025-03-26T11:08:12","slug":"gods-of-egypt-l","status":"publish","type":"post","link":"https:\/\/legendnilecruise.com\/de\/gotter-des-alten-agyptens\/gotter-agyptens-l\/","title":{"rendered":"G\u00f6tter von \u00c4gypten l"},"content":{"rendered":"<p>G\u00f6ttliche Besch\u00fctzer und Sch\u00f6pfer im alten \u00c4gypten<\/p>\n<p><img fetchpriority=\"high\" decoding=\"async\" class=\"wp-image-13806 aligncenter\" src=\"https:\/\/legendnilecruise.com\/wp-content\/uploads\/2025\/03\/Gods-Of-Egypt-l-300x200.jpg\" alt=\"\" width=\"462\" height=\"308\" srcset=\"https:\/\/legendnilecruise.com\/wp-content\/uploads\/2025\/03\/Gods-Of-Egypt-l-300x200.jpg 300w, https:\/\/legendnilecruise.com\/wp-content\/uploads\/2025\/03\/Gods-Of-Egypt-l.jpg 612w\" sizes=\"(max-width: 462px) 100vw, 462px\" \/><\/p>\n<p>&nbsp;<\/p>\n<h3 style=\"text-align: center;\"><strong>Die G\u00f6ttin Isis<\/strong><\/h3>\n<p style=\"text-align: center;\">Isis ist die Tochter von Geb, die Frau und Schwester von Osiris und die Mutter von Horus. Ihr Name bedeutet \"K\u00f6nigin des Throns\". Sie spielte eine bedeutende Rolle in der alt\u00e4gyptischen Mythologie und wurde als G\u00f6ttin der Magie und der Mutterschaft verehrt. Sie ist daf\u00fcr bekannt, dass sie den zerst\u00fcckelten K\u00f6rper ihres Mannes Osiris wieder zusammensetzte und ihn durch ihre magischen Kr\u00e4fte wieder zum Leben erweckte. Als Mutter von Horus wurde sie zu einem Symbol der Mutterschaft. Eine zentrale Geschichte in der \u00e4gyptischen Mythologie verdeutlicht die Rolle von Isis bei der Erschaffung der Menschheit. Als der Gott Ra alt wurde, wurde er der Menschen \u00fcberdr\u00fcssig und schickte Sekhmet, die wilde l\u00f6wenk\u00f6pfige G\u00f6ttin der Zerst\u00f6rung, um sie zu bestrafen. Sekhmet schlachtete zahllose Menschen ab und wurde zum ersten bekannten Vampir. In ihrer Verzweiflung wandte sich die Menschheit an Isis, die Mutter der G\u00f6tter und Menschen. Sie flehte Ra an, die Menschheit zu verschonen. \u00dcberw\u00e4ltigt von ihren Tr\u00e4nen, wies Ra sie an, ein purpurfarbenes Bier zu brauen und es Sekhmet anzubieten. Die G\u00f6ttin fiel, berauscht von dem Bier, in einen tiefen Schlaf und erm\u00f6glichte der Menschheit das \u00dcberleben. Aus Dankbarkeit glaubten die \u00c4gypter, dass aus Isis' Tr\u00e4nen der Nil entstand. Infolgedessen trugen Reisende, insbesondere Seefahrer, zum Schutz Amulette der Isis bei sich. Dieser Glaube trug zur weit verbreiteten Verehrung von Isis im gesamten Mittelmeerraum bei.<\/p>\n<p><img decoding=\"async\" class=\"wp-image-13829 aligncenter\" src=\"https:\/\/legendnilecruise.com\/wp-content\/uploads\/2025\/03\/Gods-Of-Egypt-l-300x252.png\" alt=\"\" width=\"384\" height=\"322\" srcset=\"https:\/\/legendnilecruise.com\/wp-content\/uploads\/2025\/03\/Gods-Of-Egypt-l-300x252.png 300w, https:\/\/legendnilecruise.com\/wp-content\/uploads\/2025\/03\/Gods-Of-Egypt-l.png 484w\" sizes=\"(max-width: 384px) 100vw, 384px\" \/><\/p>\n<p style=\"text-align: center;\">Die G\u00f6ttin Isis<\/p>\n<h2 style=\"text-align: center;\"><strong>Der Gott Osiris<\/strong><\/h2>\n<p style=\"text-align: center;\">Osiris, der Sohn von Geb und Ehemann von Isis, war der Bruder von Set und der Vater von Horus. Die alten \u00c4gypter assoziierten ihn mit Fruchtbarkeit, Landwirtschaft und Wohlstand. Nachdem er von seinem Bruder Set ermordet und von Isis wiedererweckt worden war, wurde er zum Herrscher der Unterwelt und symbolisierte das Leben nach dem Tod, die Auferstehung und die Ewigkeit. In der Halle des Gerichts wird Osiris als der Richter dargestellt, der die Herzen der Verstorbenen w\u00e4gt. Diejenigen, die ein tugendhaftes Leben gef\u00fchrt haben, d\u00fcrfen ins Jenseits gehen, w\u00e4hrend die B\u00f6sen bestraft werden. Osiris ist eine der bekanntesten Gottheiten in der alt\u00e4gyptischen Religion und wird oft als menschliche Figur dargestellt, die eine Krone tr\u00e4gt und ein Zepter und ein Ankh (das Symbol des Lebens) h\u00e4lt. Er wird h\u00e4ufig in Gr\u00fcn dargestellt, der Farbe, die mit Wiedergeburt und dem Leben nach dem Tod assoziiert wird.<\/p>\n<p><img decoding=\"async\" class=\"wp-image-13830 aligncenter\" src=\"https:\/\/legendnilecruise.com\/wp-content\/uploads\/2025\/03\/Gods-Of-Egypt-l-2-300x280.png\" alt=\"\" width=\"394\" height=\"367\" srcset=\"https:\/\/legendnilecruise.com\/wp-content\/uploads\/2025\/03\/Gods-Of-Egypt-l-2-300x280.png 300w, https:\/\/legendnilecruise.com\/wp-content\/uploads\/2025\/03\/Gods-Of-Egypt-l-2-482x450.png 482w, https:\/\/legendnilecruise.com\/wp-content\/uploads\/2025\/03\/Gods-Of-Egypt-l-2.png 520w\" sizes=\"(max-width: 394px) 100vw, 394px\" \/><\/p>\n<h3 style=\"text-align: center;\"><strong>Der Gott Horus<\/strong><\/h3>\n<p style=\"text-align: center;\">Horus ist eine der bekanntesten Gottheiten der alt\u00e4gyptischen Mythologie. Er ist der Sohn von Isis und Osiris und der R\u00e4cher seines Vaters, Osiris, der von seinem Onkel Set ermordet wurde. Horus forderte den Thron seines Vaters zur\u00fcck und wurde der Besch\u00fctzer der \u00e4gyptischen Pharaonen. Jeder \u00e4gyptische Pharao wurde als Sohn des Horus betrachtet. Horus wird oft als falkenk\u00f6pfiger Mann dargestellt. Der Falke wurde aus mehreren Gr\u00fcnden als sein Symbol gew\u00e4hlt. Der Falke schwebt nicht nur hoch am Himmel und jagt andere Lebewesen, sondern er hat auch die einzigartige F\u00e4higkeit, direkt in die Sonne zu starren, ohne zu blinzeln. Diese F\u00e4higkeit machte ihn zu einem passenden Symbol f\u00fcr Horus, den Gott des Himmels. Horus gilt als der Gott des Himmels und des Krieges. Er repr\u00e4sentiert die k\u00f6nigliche Macht der Pharaonen. Das Auge des Horus Das rechte Auge des Horus symbolisiert die Sonne, w\u00e4hrend das linke Auge f\u00fcr den Mond steht. Im Mythos verletzte Set das linke Auge von Horus, aber der Gott Thoth stellte es wieder her. Das Auge des Horus wurde f\u00fcr die alten \u00c4gypter zu einem m\u00e4chtigen Symbol f\u00fcr Schutz und Heilung. Es wurde oft als Schutzamulett verwendet und fand in verschiedenen Aspekten des \u00e4gyptischen Lebens, einschlie\u00dflich Mathematik und Medizin, Verwendung. Zentren der Verehrung Der ber\u00fchmteste Tempel, der Horus gewidmet ist, ist der Tempel von Edfu. Au\u00dferdem war Horus mit Hathor, der G\u00f6ttin der Liebe, Sch\u00f6nheit und Freude, verheiratet. Ihre Hochzeit ist in den Tempeln von Edfu und Dendera abgebildet.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-13833 aligncenter\" src=\"https:\/\/legendnilecruise.com\/wp-content\/uploads\/2025\/03\/Gods-Of-Egypt-l-1-300x242.jpg\" alt=\"\" width=\"369\" height=\"298\" srcset=\"https:\/\/legendnilecruise.com\/wp-content\/uploads\/2025\/03\/Gods-Of-Egypt-l-1-300x242.jpg 300w, https:\/\/legendnilecruise.com\/wp-content\/uploads\/2025\/03\/Gods-Of-Egypt-l-1.jpg 531w\" sizes=\"(max-width: 369px) 100vw, 369px\" \/><\/p>\n<p style=\"text-align: center;\">Bild des Gottes Horus<\/p>\n<h3 style=\"text-align: center;\"><strong>Der Gott Amun<\/strong><\/h3>\n<p style=\"text-align: center;\">Theben, die alte Hauptstadt \u00c4gyptens, war die Hauptwirkungsst\u00e4tte des Gottes Amun. Mit der Zeit vereinigte er sich mit dem Sonnengott Ra und bildete die m\u00e4chtige Gottheit Amun-Ra. Seine Familie bestand aus einer Dreiergruppe: Amun selbst, seine Frau Mut und ihr Sohn Khonsu. Amun besa\u00df pr\u00e4chtige Tempel in Karnak. K\u00f6nig Ahmose trug bekanntlich eine goldene Statue des Amun in die Schlacht gegen die Hyksos, und nach seinem Sieg wurde es f\u00fcr die \u00e4gyptischen Pharaonen zur Tradition, in Karnak Tempel oder Denkm\u00e4ler zu errichten. Als Fruchtbarkeitsgott wurde Amun oft als Mann in einem gefalteten Kilt mit einem erigierten Phallus oder als Widder dargestellt. Diese Assoziation mit dem Widder ist in der Stra\u00dfe der Widder in Karnak offensichtlich. Der Name 'Amun' bedeutet 'der Verborgene' oder 'das Geheimnis', und seine Ableitung 'Amen' ist in vielen Sprachen der Welt zu einem universellen Begriff geworden.\"<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-13852 aligncenter\" src=\"https:\/\/legendnilecruise.com\/wp-content\/uploads\/2025\/03\/Gods-Of-Egypt-l-3-300x187.png\" alt=\"\" width=\"448\" height=\"279\" srcset=\"https:\/\/legendnilecruise.com\/wp-content\/uploads\/2025\/03\/Gods-Of-Egypt-l-3-300x187.png 300w, https:\/\/legendnilecruise.com\/wp-content\/uploads\/2025\/03\/Gods-Of-Egypt-l-3.png 597w\" sizes=\"(max-width: 448px) 100vw, 448px\" \/><\/p>\n<p style=\"text-align: center;\">Bes: Bes war der alt\u00e4gyptische Gott der Fr\u00f6hlichkeit, der Musik und des Schutzes. Er galt als Besch\u00fctzer von Kindern, schwangeren Frauen, Besch\u00fctzer der Schl\u00e4fer - Besch\u00fctzer der Lebenden und der Toten. Bes wurde oft als zwergenhafte Figur mit einem gro\u00dfen Kopf, abstehenden Ohren und einem H\u00e4ngebauch dargestellt. Sein Gesichtsausdruck war eine einzigartige Mischung aus Lachen und Wildheit. Bes wurde mit Musikinstrumenten in Verbindung gebracht, von denen man glaubte, dass sie b\u00f6se Geister vertreiben und den Menschen Freude bringen. Er wurde h\u00e4ufig mit Schlangen, Messern oder Schwertern dargestellt, die seine Schutzkr\u00e4fte symbolisieren sollten. Diese gef\u00e4hrlichen Gegenst\u00e4nde sollten schwangere Frauen w\u00e4hrend der Geburt vor Schaden bewahren und Schlafende vor Albtr\u00e4umen sch\u00fctzen. Einige der ber\u00fchmtesten Darstellungen von Bes finden sich in den Tempeln von Edfu, Philae und Dendera.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-13853 aligncenter\" src=\"https:\/\/legendnilecruise.com\/wp-content\/uploads\/2025\/03\/Gods-Of-Egypt-l-4-300x244.png\" alt=\"\" width=\"370\" height=\"301\" srcset=\"https:\/\/legendnilecruise.com\/wp-content\/uploads\/2025\/03\/Gods-Of-Egypt-l-4-300x244.png 300w, https:\/\/legendnilecruise.com\/wp-content\/uploads\/2025\/03\/Gods-Of-Egypt-l-4.png 448w\" sizes=\"(max-width: 370px) 100vw, 370px\" \/><\/p>\n<p style=\"text-align: center;\">Der Gott Bes<\/p>\n<h3 style=\"text-align: center;\"><strong>Der Gott Thoth (oder Tehuti)<\/strong><\/h3>\n<p style=\"text-align: center;\">Thoth war der alt\u00e4gyptische Gott des Mondes, der Weisheit, des Wissens und der Schrift. Er wurde oft als Mann mit dem Kopf eines Ibis dargestellt. Eine andere g\u00e4ngige Darstellung von Thoth war die eines Pavians, der eine Papyrusrolle und einen Griffel h\u00e4lt. Als Schutzherr der Schrift \u00fcberwachte Thoth die gesamte schriftliche Kommunikation, von k\u00f6niglichen Dekreten in Tempeln bis hin zu allt\u00e4glichen Aufzeichnungen. Er wurde eng mit dem Gott Horus in Verbindung gebracht, da ihm die Wiederherstellung von Horus' Auge zugeschrieben wurde. Thoth spielte auch eine entscheidende Rolle in der Halle des Gerichts im Jenseits, wo er die Herzen der Toten (ihre guten und schlechten Taten) aufzeichnete. Er galt als der Herr des Hauses des Lebens, in dem die Geheimnisse des Wissens und der Weisheit aufbewahrt wurden.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-13855 aligncenter\" src=\"https:\/\/legendnilecruise.com\/wp-content\/uploads\/2025\/03\/Gods-Of-Egypt-l-5-296x300.png\" alt=\"\" width=\"337\" height=\"342\" srcset=\"https:\/\/legendnilecruise.com\/wp-content\/uploads\/2025\/03\/Gods-Of-Egypt-l-5-296x300.png 296w, https:\/\/legendnilecruise.com\/wp-content\/uploads\/2025\/03\/Gods-Of-Egypt-l-5-100x100.png 100w, https:\/\/legendnilecruise.com\/wp-content\/uploads\/2025\/03\/Gods-Of-Egypt-l-5-445x450.png 445w, https:\/\/legendnilecruise.com\/wp-content\/uploads\/2025\/03\/Gods-Of-Egypt-l-5.png 486w\" sizes=\"(max-width: 337px) 100vw, 337px\" \/><\/p>\n<p style=\"text-align: center;\">Der Gott Thoth (oder Tehuti)<\/p>\n<h3 style=\"text-align: center;\"><strong>G\u00f6ttin Hathor<\/strong><\/h3>\n<p style=\"text-align: center;\">Hathor war die alt\u00e4gyptische G\u00f6ttin der Freude, der Musik, des Tanzes und der Mutterschaft. Sie wurde oft als sch\u00f6ne Frau dargestellt, die einen Kopfschmuck mit den H\u00f6rnern einer Kuh und der Sonnenscheibe trug. Hathor war eng mit Musik und Tanz verbunden, wie das Sistrum, ein Musikinstrument in Form einer Rassel, das ihr heilig war, beweist. Sie wurde oft dargestellt, wie sie bei der Geburt eines Kindes auf dem Sistrum spielt, um die Freude und das Gl\u00fcck zu symbolisieren, die mit dem neuen Leben einhergehen, und um eine fr\u00f6hliche Atmosph\u00e4re zu schaffen. Das Bild der sieben Hathoren, die der Geburt eines Kindes vorstanden, ist ein bekanntes Motiv in der \u00e4gyptischen Kunst. Hathor wurde in ganz \u00c4gypten verehrt und war mit vielen Tempeln verbunden. Die Hathor-S\u00e4ulen, die mit dem Kopf der Hathor gekr\u00f6nt wurden, waren ein h\u00e4ufiges architektonisches Merkmal in \u00e4gyptischen Tempeln, wie zum Beispiel im Tempel der Hatschepsut und in Dendera.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-13857 aligncenter\" src=\"https:\/\/legendnilecruise.com\/wp-content\/uploads\/2025\/03\/Gods-Of-Egypt-l-6-243x300.png\" alt=\"\" width=\"301\" height=\"372\" srcset=\"https:\/\/legendnilecruise.com\/wp-content\/uploads\/2025\/03\/Gods-Of-Egypt-l-6-243x300.png 243w, https:\/\/legendnilecruise.com\/wp-content\/uploads\/2025\/03\/Gods-Of-Egypt-l-6-365x450.png 365w, https:\/\/legendnilecruise.com\/wp-content\/uploads\/2025\/03\/Gods-Of-Egypt-l-6.png 547w\" sizes=\"(max-width: 301px) 100vw, 301px\" \/><\/p>\n<p style=\"text-align: center;\">G\u00f6ttin Hathor<\/p>","protected":false},"excerpt":{"rendered":"<p>G\u00f6ttliche Besch\u00fctzer und Sch\u00f6pfer des alten \u00c4gyptens Die G\u00f6ttin Isis Isis ist die Tochter von Geb, die Frau und Schwester von Osiris und die Mutter von Horus. Ihr Name bedeutet \"K\u00f6nigin des Throns\". Sie spielte eine bedeutende Rolle in der alt\u00e4gyptischen Mythologie und wurde als G\u00f6ttin der Magie und der Mutterschaft verehrt. Sie ist bekannt als [...]<\/p>","protected":false},"author":1,"featured_media":13875,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[75],"tags":[],"class_list":["post-13803","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-gods-of-ancient-egypt"],"_links":{"self":[{"href":"https:\/\/legendnilecruise.com\/de\/wp-json\/wp\/v2\/posts\/13803","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/legendnilecruise.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/legendnilecruise.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/legendnilecruise.com\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/legendnilecruise.com\/de\/wp-json\/wp\/v2\/comments?post=13803"}],"version-history":[{"count":3,"href":"https:\/\/legendnilecruise.com\/de\/wp-json\/wp\/v2\/posts\/13803\/revisions"}],"predecessor-version":[{"id":13873,"href":"https:\/\/legendnilecruise.com\/de\/wp-json\/wp\/v2\/posts\/13803\/revisions\/13873"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/legendnilecruise.com\/de\/wp-json\/wp\/v2\/media\/13875"}],"wp:attachment":[{"href":"https:\/\/legendnilecruise.com\/de\/wp-json\/wp\/v2\/media?parent=13803"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/legendnilecruise.com\/de\/wp-json\/wp\/v2\/categories?post=13803"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/legendnilecruise.com\/de\/wp-json\/wp\/v2\/tags?post=13803"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}