{"id":13392,"date":"2025-03-26T09:52:18","date_gmt":"2025-03-26T09:52:18","guid":{"rendered":"https:\/\/legendnilecruise.com\/?p=13392"},"modified":"2025-03-26T09:57:55","modified_gmt":"2025-03-26T09:57:55","slug":"luxor-museum","status":"publish","type":"post","link":"https:\/\/legendnilecruise.com\/de\/artikel\/luxor-museum\/","title":{"rendered":"Luxor-Museum"},"content":{"rendered":"<div class=\"article-part\" data-v-16884332=\"\">\n<blockquote>\n<h4 style=\"text-align: left;\" data-v-16884332=\"\">Luxor-Museum<\/h4>\n<\/blockquote>\n<p data-v-16884332=\"\">Das Museum wurde am 12. Dezember 1975 er\u00f6ffnet. Die Cache-Halle wurde am 12. Dezember 1991 er\u00f6ffnet. Am 19. Mai 2004 wurde dann der Saal \"Glory of Thebes\" er\u00f6ffnet. Das Museum liegt an der Nil-Corniche in Luxor und hat eine Fl\u00e4che von etwa 5327 Quadratmetern. An das Museum schlie\u00dft sich ein Garten an, in dem 5 arch\u00e4ologische St\u00fccke ausgestellt sind. Das Museum besteht aus 6 S\u00e4len: dem Eingang, dem ersten Stockwerk, dem zweiten Stockwerk, dem Cache-Saal und dem Saal der Herrlichkeit von Theben. Das Museum besteht aus zwei Etagen.<\/p>\n<\/div>\n<div class=\"article-part\" data-v-16884332=\"\">\n<h4 data-v-16884332=\"\">Der erste Stock<\/h4>\n<p data-v-16884332=\"\">enth\u00e4lt eine Sammlung seltener Artefakte, die in Luxor gefunden wurden. Die wichtigste Statue im Museum ist eine Alabasterstatue des Gottes Sobek mit K\u00f6nig Amenhotep III. Au\u00dferdem gibt es eine herrliche Statue von K\u00f6nig Thutmose III. aus Schiefer. Ein Granitkopf von K\u00f6nig Amenhotep III. und ein Kopf der G\u00f6ttin Hathor in Form einer Kuh. Eine Statue des Gottes Amun und ein seltener Kopf von K\u00f6nig Senusret III. Au\u00dferdem gibt es die Stele von Karnak, die einen hieroglyphischen Text \u00fcber den Kampf der Herrscher von Theben gegen die Hyksos, die erste ausl\u00e4ndische Invasion \u00c4gyptens und die Befreiung des Landes von den Eindringlingen enth\u00e4lt.<\/p>\n<\/div>\n<div class=\"article-part\" data-v-16884332=\"\">\n<h4 data-v-16884332=\"\">Obergeschoss<\/h4>\n<p data-v-16884332=\"\">Der gr\u00f6\u00dfte Teil des oberen Stockwerks ist K\u00f6nig Echnaton gewidmet. Wir sehen eine Sammlung seiner Statuen, einige Inschriften mit seiner Frau K\u00f6nigin Nofretete und seinen Kindern sowie einige M\u00f6bel, Ger\u00e4te, Schmuck und Amulette. Wir finden auch koptische Gem\u00e4lde (Ikonen).<\/p>\n<\/div>\n<div class=\"article-part\" data-v-16884332=\"\">\n<h4 data-v-16884332=\"\">Cache-Halle<\/h4>\n<p data-v-16884332=\"\">Am 22. Januar 1989 wollte sich ein Arbeiter im Karnak-Tempel aufw\u00e4rmen. Da der Boden des Tempels damals aus Erde bestand, grub er ein Loch, um darin Holz f\u00fcr ein Feuer zu legen. Gl\u00fccklicherweise fand er beim Graben zuf\u00e4llig den Kopf einer Statue. Er informierte die \u00e4gyptischen Beh\u00f6rden, die mit den Ausgrabungen begannen und dabei den so genannten Karnak-Tempelcache fanden. Zu den wichtigsten Funden geh\u00f6ren Statuen von K\u00f6nig Amenhotep III, Amun und Hathor. Das Museum hat einen ganzen Saal eingerichtet, um viele der in diesem Cache gefundenen Gegenst\u00e4nde auszustellen. Der Fund wurde am 22. Januar 1989 entdeckt, und der Saal wurde am 12. Dezember 1991 er\u00f6ffnet. Eine der sch\u00f6nsten Statuen, die in dem Cache gefunden wurden, ist die Doppelstatue von K\u00f6nig Horemheb. Es gibt auch eine weitere Statue von K\u00f6nig Horemheb, der vor Amun-Ra kniet und ihm zwei Kr\u00fcge Wein anbietet. Au\u00dferdem gibt es eine zweieinhalb Meter hohe Statue von K\u00f6nig Amenhotep III. aus rosa Quarzit.<\/p>\n<\/div>\n<div class=\"article-part\" data-v-16884332=\"\">\n<h4 data-v-16884332=\"\">Das Museum enth\u00e4lt au\u00dferdem<\/h4>\n<p data-v-16884332=\"\">Der zerlegte Kriegswagen von K\u00f6nig Tutanchamun, der in seinem Grab gefunden wurde und f\u00fcr die Jagd und das Training verwendet wurde. K\u00f6nigliche Mumien von K\u00f6nig Ahmose I., der die Hyksos vertrieb, und K\u00f6nig Ramses I., dem Gr\u00fcnder der Neunzehnten Dynastie. Einzigartige Werkzeuge, die die architektonischen und ingenieurtechnischen F\u00e4higkeiten der alten \u00c4gypter demonstrieren, wie z. B. ein Zimmermannswinkel, der zum Messen von Geb\u00e4udewinkeln verwendet wurde, ein h\u00f6lzernes Werkzeug in Form des Buchstabens \"A\" mit einer Schnur und einem birnenf\u00f6rmigen Steinst\u00fcck, das zum Messen von horizontalen Fl\u00e4chen verwendet wurde, sowie ein vertikales Senklot. Zwei von K\u00f6nig Kamose errichtete Stelen, die seinen Sieg \u00fcber die Hyksos darstellen. Eine Statue des Schreibers und Weisen Amenhotep, Sohn des Hapu, Ingenieur von K\u00f6nig Amenhotep III. Ein kleiner Obelisk von K\u00f6nig Ramses III.<\/p>\n<div class=\"q-img q-img--menu article-image\" role=\"img\" data-v-16884332=\"\">\n<div><\/div>\n<div class=\"q-img__container absolute-full\"><img fetchpriority=\"high\" decoding=\"async\" class=\"alignnone  wp-image-13411\" src=\"https:\/\/legendnilecruise.com\/wp-content\/uploads\/2025\/03\/1_HLPOhlE-300x220.png\" alt=\"\" width=\"850\" height=\"623\" srcset=\"https:\/\/legendnilecruise.com\/wp-content\/uploads\/2025\/03\/1_HLPOhlE-300x220.png 300w, https:\/\/legendnilecruise.com\/wp-content\/uploads\/2025\/03\/1_HLPOhlE.png 457w\" sizes=\"(max-width: 850px) 100vw, 850px\" \/><\/div>\n<div class=\"q-img__content absolute-full q-anchor--skip\"><\/div>\n<\/div>\n<\/div>\n<div class=\"article-part\" data-v-16884332=\"\">\n<p data-v-16884332=\"\">Fassade des Luxor-Museums und des Museumsgartens mit k\u00f6niglichen Statuen<\/p>\n<div class=\"q-img q-img--menu article-image\" role=\"img\" data-v-16884332=\"\">\n<div><\/div>\n<div class=\"q-img__container absolute-full\"><img decoding=\"async\" class=\"alignnone  wp-image-13410\" src=\"https:\/\/legendnilecruise.com\/wp-content\/uploads\/2025\/03\/2_imkzYju-300x206.png\" alt=\"\" width=\"1014\" height=\"696\" srcset=\"https:\/\/legendnilecruise.com\/wp-content\/uploads\/2025\/03\/2_imkzYju-300x206.png 300w, https:\/\/legendnilecruise.com\/wp-content\/uploads\/2025\/03\/2_imkzYju.png 448w\" sizes=\"(max-width: 1014px) 100vw, 1014px\" \/><\/div>\n<div class=\"q-img__content absolute-full q-anchor--skip\"><\/div>\n<\/div>\n<\/div>\n<div class=\"article-part\" data-v-16884332=\"\">\n<p data-v-16884332=\"\">Der Saal der Herrlichkeit von Theben im Erdgeschoss des Luxor-Museums<\/p>\n<div class=\"q-img q-img--menu article-image\" role=\"img\" data-v-16884332=\"\">\n<div><\/div>\n<div class=\"q-img__container absolute-full\"><img decoding=\"async\" class=\"alignnone  wp-image-13409\" src=\"https:\/\/legendnilecruise.com\/wp-content\/uploads\/2025\/03\/3_e2xKegO-300x260.png\" alt=\"\" width=\"1064\" height=\"922\" srcset=\"https:\/\/legendnilecruise.com\/wp-content\/uploads\/2025\/03\/3_e2xKegO-300x260.png 300w, https:\/\/legendnilecruise.com\/wp-content\/uploads\/2025\/03\/3_e2xKegO.png 432w\" sizes=\"(max-width: 1064px) 100vw, 1064px\" \/><\/div>\n<div class=\"q-img__content absolute-full q-anchor--skip\"><\/div>\n<\/div>\n<\/div>\n<div class=\"article-part\" data-v-16884332=\"\">\n<p data-v-16884332=\"\">Statue des Gottes Sobek und Amenhotep III. im Luxor-Museum<\/p>\n<div class=\"q-img q-img--menu article-image\" role=\"img\" data-v-16884332=\"\">\n<div><\/div>\n<div class=\"q-img__container absolute-full\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone  wp-image-13407\" src=\"https:\/\/legendnilecruise.com\/wp-content\/uploads\/2025\/03\/4_0mIstMa-228x300.png\" alt=\"\" width=\"824\" height=\"1084\" srcset=\"https:\/\/legendnilecruise.com\/wp-content\/uploads\/2025\/03\/4_0mIstMa-228x300.png 228w, https:\/\/legendnilecruise.com\/wp-content\/uploads\/2025\/03\/4_0mIstMa-342x450.png 342w, https:\/\/legendnilecruise.com\/wp-content\/uploads\/2025\/03\/4_0mIstMa.png 464w\" sizes=\"(max-width: 824px) 100vw, 824px\" \/><\/div>\n<div class=\"q-img__content absolute-full q-anchor--skip\"><\/div>\n<\/div>\n<\/div>\n<div class=\"article-part\" data-v-16884332=\"\">\n<p data-v-16884332=\"\">Statue von K\u00f6nig Thutmose III. aus grauem Basalt, gefunden in Karnak im Jahr 1904<\/p>\n<div class=\"q-img q-img--menu article-image\" role=\"img\" data-v-16884332=\"\">\n<div><\/div>\n<div class=\"q-img__container absolute-full\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone  wp-image-13406\" src=\"https:\/\/legendnilecruise.com\/wp-content\/uploads\/2025\/03\/5_see97Ya-224x300.png\" alt=\"\" width=\"1080\" height=\"1446\" srcset=\"https:\/\/legendnilecruise.com\/wp-content\/uploads\/2025\/03\/5_see97Ya-224x300.png 224w, https:\/\/legendnilecruise.com\/wp-content\/uploads\/2025\/03\/5_see97Ya-336x450.png 336w, https:\/\/legendnilecruise.com\/wp-content\/uploads\/2025\/03\/5_see97Ya.png 417w\" sizes=\"(max-width: 1080px) 100vw, 1080px\" \/><\/div>\n<div class=\"q-img__content absolute-full q-anchor--skip\"><\/div>\n<\/div>\n<\/div>\n<div class=\"article-part\" data-v-16884332=\"\">\n<p data-v-16884332=\"\">Doppelstatue aus Granit f\u00fcr den Gott Amun und seine Frau, die G\u00f6ttin Mut, dazwischen zwei Kartuschen von K\u00f6nig Seti I.<\/p>\n<div class=\"q-img q-img--menu article-image\" role=\"img\" data-v-16884332=\"\">\n<div><\/div>\n<div class=\"q-img__container absolute-full\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone  wp-image-13405\" src=\"https:\/\/legendnilecruise.com\/wp-content\/uploads\/2025\/03\/6_6hLdqrE-267x300.png\" alt=\"\" width=\"766\" height=\"861\" srcset=\"https:\/\/legendnilecruise.com\/wp-content\/uploads\/2025\/03\/6_6hLdqrE-267x300.png 267w, https:\/\/legendnilecruise.com\/wp-content\/uploads\/2025\/03\/6_6hLdqrE-401x450.png 401w, https:\/\/legendnilecruise.com\/wp-content\/uploads\/2025\/03\/6_6hLdqrE.png 466w\" sizes=\"(max-width: 766px) 100vw, 766px\" \/><\/div>\n<div class=\"q-img__content absolute-full q-anchor--skip\"><\/div>\n<\/div>\n<\/div>\n<div class=\"article-part\" data-v-16884332=\"\">\n<p data-v-16884332=\"\">Eine Kalksteinstele des Kamose mit der Inschrift seines Sieges \u00fcber die Hyksos, die in Karnak gefunden wurde.<\/p>\n<div class=\"q-img q-img--menu article-image\" role=\"img\" data-v-16884332=\"\">\n<div><\/div>\n<div class=\"q-img__container absolute-full\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone  wp-image-13413\" src=\"https:\/\/legendnilecruise.com\/wp-content\/uploads\/2025\/03\/7_kPdka3t-193x300.png\" alt=\"\" width=\"791\" height=\"1230\" srcset=\"https:\/\/legendnilecruise.com\/wp-content\/uploads\/2025\/03\/7_kPdka3t-193x300.png 193w, https:\/\/legendnilecruise.com\/wp-content\/uploads\/2025\/03\/7_kPdka3t-290x450.png 290w, https:\/\/legendnilecruise.com\/wp-content\/uploads\/2025\/03\/7_kPdka3t.png 343w\" sizes=\"(max-width: 791px) 100vw, 791px\" \/><\/div>\n<div class=\"q-img__content absolute-full q-anchor--skip\"><\/div>\n<\/div>\n<\/div>\n<div class=\"article-part\" data-v-16884332=\"\">\n<p data-v-16884332=\"\">Eine Statue des Weisen und Wesirs Amenhotep, Sohn des Hapu, in Form eines Schreibers, aus schwarzem Granit.<\/p>\n<div class=\"q-img q-img--menu article-image\" role=\"img\" data-v-16884332=\"\">\n<div><\/div>\n<div class=\"q-img__container absolute-full\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone  wp-image-13404\" src=\"https:\/\/legendnilecruise.com\/wp-content\/uploads\/2025\/03\/8_BOfoDeE-198x300.png\" alt=\"\" width=\"928\" height=\"1406\" srcset=\"https:\/\/legendnilecruise.com\/wp-content\/uploads\/2025\/03\/8_BOfoDeE-198x300.png 198w, https:\/\/legendnilecruise.com\/wp-content\/uploads\/2025\/03\/8_BOfoDeE.png 380w\" sizes=\"(max-width: 928px) 100vw, 928px\" \/><\/div>\n<div class=\"q-img__content absolute-full q-anchor--skip\"><\/div>\n<\/div>\n<\/div>\n<div class=\"article-part\" data-v-16884332=\"\">\n<p data-v-16884332=\"\">Eine Statue von K\u00f6nig Amenhotep III. aus Quarzit.<\/p>\n<div class=\"q-img q-img--menu article-image\" role=\"img\" data-v-16884332=\"\">\n<div><\/div>\n<div class=\"q-img__container absolute-full\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone  wp-image-13403\" src=\"https:\/\/legendnilecruise.com\/wp-content\/uploads\/2025\/03\/9_13PxqjO-293x300.png\" alt=\"\" width=\"1037\" height=\"1062\" srcset=\"https:\/\/legendnilecruise.com\/wp-content\/uploads\/2025\/03\/9_13PxqjO-293x300.png 293w, https:\/\/legendnilecruise.com\/wp-content\/uploads\/2025\/03\/9_13PxqjO-439x450.png 439w, https:\/\/legendnilecruise.com\/wp-content\/uploads\/2025\/03\/9_13PxqjO.png 559w\" sizes=\"(max-width: 1037px) 100vw, 1037px\" \/><\/div>\n<div class=\"q-img__content absolute-full q-anchor--skip\"><\/div>\n<\/div>\n<\/div>\n<div class=\"article-part\" data-v-16884332=\"\">\n<p data-v-16884332=\"\">Die Dreifachwand von K\u00f6nig Echnaton aus dem Karnak-Tempel mit Szenen des t\u00e4glichen Lebens, von denen die sch\u00f6nste einen Bauern zeigt, der ein Kalb f\u00fcttert, und zwei G\u00e4nse, die Getreide aus einem offenen Krug picken.<\/p>\n<div class=\"q-img q-img--menu article-image\" role=\"img\" data-v-16884332=\"\">\n<div><\/div>\n<div class=\"q-img__container absolute-full\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone  wp-image-13401\" src=\"https:\/\/legendnilecruise.com\/wp-content\/uploads\/2025\/03\/10_BeXXREK-300x245.png\" alt=\"\" width=\"812\" height=\"663\" srcset=\"https:\/\/legendnilecruise.com\/wp-content\/uploads\/2025\/03\/10_BeXXREK-300x245.png 300w, https:\/\/legendnilecruise.com\/wp-content\/uploads\/2025\/03\/10_BeXXREK.png 478w\" sizes=\"(max-width: 812px) 100vw, 812px\" \/><\/div>\n<div class=\"q-img__content absolute-full q-anchor--skip\"><\/div>\n<\/div>\n<\/div>\n<div class=\"article-part\" data-v-16884332=\"\">\n<p data-v-16884332=\"\">Echnaton im Luxor-Museum<\/p>\n<div class=\"q-img q-img--menu article-image\" role=\"img\" data-v-16884332=\"\">\n<div><\/div>\n<div class=\"q-img__container absolute-full\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone  wp-image-13400\" src=\"https:\/\/legendnilecruise.com\/wp-content\/uploads\/2025\/03\/11_zNQivXD-300x256.png\" alt=\"\" width=\"896\" height=\"765\" srcset=\"https:\/\/legendnilecruise.com\/wp-content\/uploads\/2025\/03\/11_zNQivXD-300x256.png 300w, https:\/\/legendnilecruise.com\/wp-content\/uploads\/2025\/03\/11_zNQivXD.png 508w\" sizes=\"(max-width: 896px) 100vw, 896px\" \/><\/div>\n<div class=\"q-img__content absolute-full q-anchor--skip\"><\/div>\n<\/div>\n<\/div>\n<div class=\"article-part\" data-v-16884332=\"\">\n<p data-v-16884332=\"\">Eine kolorierte Zeichnung von Amenhotep III., Fragmente einer Gipsplatte, die K\u00f6nig Amenhotep III. darstellt, hinter ihm sind Teile zu sehen, die seine Mutter (Mut Am Awia) darstellen, die ihre Hand auf seine Schulter legt, und vor dem K\u00f6nig erscheinen zwei Strau\u00dfenfederf\u00e4cher. Am unteren Rand der Tafel sind Szenen einiger Gefangener zu sehen, und vor dem K\u00f6nig ist eine Kartusche mit dem Namen des K\u00f6nigs zu lesen.<\/p>\n<div class=\"q-img q-img--menu article-image\" role=\"img\" data-v-16884332=\"\">\n<div><\/div>\n<div class=\"q-img__container absolute-full\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone  wp-image-13399\" src=\"https:\/\/legendnilecruise.com\/wp-content\/uploads\/2025\/03\/12_BXYwIUX-300x169.png\" alt=\"\" width=\"941\" height=\"530\" srcset=\"https:\/\/legendnilecruise.com\/wp-content\/uploads\/2025\/03\/12_BXYwIUX-300x169.png 300w, https:\/\/legendnilecruise.com\/wp-content\/uploads\/2025\/03\/12_BXYwIUX.png 555w\" sizes=\"(max-width: 941px) 100vw, 941px\" \/><\/div>\n<div class=\"q-img__content absolute-full q-anchor--skip\"><\/div>\n<\/div>\n<\/div>\n<div class=\"article-part\" data-v-16884332=\"\">\n<p data-v-16884332=\"\">Mumie von K\u00f6nig Ahmose I. im Luxor-Museum<\/p>\n<div class=\"q-img q-img--menu article-image\" role=\"img\" data-v-16884332=\"\">\n<div><img loading=\"lazy\" decoding=\"async\" class=\"alignnone  wp-image-13398\" src=\"https:\/\/legendnilecruise.com\/wp-content\/uploads\/2025\/03\/13_BxJM14z-254x300.png\" alt=\"\" width=\"1072\" height=\"1266\" srcset=\"https:\/\/legendnilecruise.com\/wp-content\/uploads\/2025\/03\/13_BxJM14z-254x300.png 254w, https:\/\/legendnilecruise.com\/wp-content\/uploads\/2025\/03\/13_BxJM14z-381x450.png 381w, https:\/\/legendnilecruise.com\/wp-content\/uploads\/2025\/03\/13_BxJM14z.png 397w\" sizes=\"(max-width: 1072px) 100vw, 1072px\" \/><\/div>\n<div class=\"q-img__container absolute-full\"><\/div>\n<div class=\"q-img__content absolute-full q-anchor--skip\"><\/div>\n<\/div>\n<\/div>\n<div class=\"article-part\" data-v-16884332=\"\">\n<p data-v-16884332=\"\">Ein koptisches Grabmal aus dem 6. Jahrhundert n. Chr. in Form eines halbrunden Steins mit einem Kreuz in der Mitte, auf dem ein Adler seine Schwingen ausbreitet.<\/p>\n<div class=\"q-img q-img--menu article-image\" role=\"img\" data-v-16884332=\"\">\n<div><\/div>\n<div class=\"q-img__container absolute-full\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone  wp-image-13397\" src=\"https:\/\/legendnilecruise.com\/wp-content\/uploads\/2025\/03\/14_uf4knVO-254x300.png\" alt=\"\" width=\"953\" height=\"1126\" srcset=\"https:\/\/legendnilecruise.com\/wp-content\/uploads\/2025\/03\/14_uf4knVO-254x300.png 254w, https:\/\/legendnilecruise.com\/wp-content\/uploads\/2025\/03\/14_uf4knVO-381x450.png 381w, https:\/\/legendnilecruise.com\/wp-content\/uploads\/2025\/03\/14_uf4knVO.png 397w\" sizes=\"(max-width: 953px) 100vw, 953px\" \/><\/div>\n<div class=\"q-img__content absolute-full q-anchor--skip\"><\/div>\n<\/div>\n<\/div>\n<div class=\"article-part\" data-v-16884332=\"\">\n<p data-v-16884332=\"\">Eine Tafel aus Kalkstein, die zu einer Kirche im Karnak-Tempel geh\u00f6rte. Es handelt sich um einen Rundbogen, der von zwei S\u00e4ulen getragen wird. Im Inneren des Bogens befindet sich oben eine Muschel, und zwischen den S\u00e4ulen ist ein Fisch dargestellt, da der Fisch den christlichen Glauben symbolisiert.<\/p>\n<div class=\"q-img q-img--menu article-image\" role=\"img\" data-v-16884332=\"\">\n<div><img loading=\"lazy\" decoding=\"async\" class=\"alignnone  wp-image-13396\" src=\"https:\/\/legendnilecruise.com\/wp-content\/uploads\/2025\/03\/15_e1cHIlo-300x159.png\" alt=\"\" width=\"940\" height=\"498\" srcset=\"https:\/\/legendnilecruise.com\/wp-content\/uploads\/2025\/03\/15_e1cHIlo-300x159.png 300w, https:\/\/legendnilecruise.com\/wp-content\/uploads\/2025\/03\/15_e1cHIlo.png 448w\" sizes=\"(max-width: 940px) 100vw, 940px\" \/><\/div>\n<div class=\"q-img__container absolute-full\"><\/div>\n<div class=\"q-img__content absolute-full q-anchor--skip\"><\/div>\n<\/div>\n<\/div>\n<div class=\"article-part\" data-v-16884332=\"\">\n<p data-v-16884332=\"\">Der obere Teil einer Apsis aus Kalkstein aus dem 3. Jahrhundert n. Chr. ist mit Pflanzenmotiven verziert, die einen Adler darstellen, hinter dem sich eine Muschel befindet, und endet unten mit einem Teil des Kreuzes.<\/p>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Luxor Museum Das Museum wurde am 12. Dezember 1975 er\u00f6ffnet. Die Cache-Halle wurde am 12. Dezember 1991 er\u00f6ffnet. Am 19. Mai 2004 wurde dann der Saal Glory of Thebes er\u00f6ffnet. Das Museum liegt an der Nilk\u00fcste in Luxor und hat eine Fl\u00e4che von etwa 5327 Quadratmetern. An das Museum angeschlossen ist [...]<\/p>","protected":false},"author":1,"featured_media":13426,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[136],"tags":[],"class_list":["post-13392","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-articles"],"_links":{"self":[{"href":"https:\/\/legendnilecruise.com\/de\/wp-json\/wp\/v2\/posts\/13392","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/legendnilecruise.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/legendnilecruise.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/legendnilecruise.com\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/legendnilecruise.com\/de\/wp-json\/wp\/v2\/comments?post=13392"}],"version-history":[{"count":5,"href":"https:\/\/legendnilecruise.com\/de\/wp-json\/wp\/v2\/posts\/13392\/revisions"}],"predecessor-version":[{"id":13445,"href":"https:\/\/legendnilecruise.com\/de\/wp-json\/wp\/v2\/posts\/13392\/revisions\/13445"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/legendnilecruise.com\/de\/wp-json\/wp\/v2\/media\/13426"}],"wp:attachment":[{"href":"https:\/\/legendnilecruise.com\/de\/wp-json\/wp\/v2\/media?parent=13392"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/legendnilecruise.com\/de\/wp-json\/wp\/v2\/categories?post=13392"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/legendnilecruise.com\/de\/wp-json\/wp\/v2\/tags?post=13392"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}