{"id":13125,"date":"2025-03-26T08:12:40","date_gmt":"2025-03-26T08:12:40","guid":{"rendered":"https:\/\/legendnilecruise.com\/?p=13125"},"modified":"2025-03-26T08:47:39","modified_gmt":"2025-03-26T08:47:39","slug":"valley-of-the-kings-part-ii","status":"publish","type":"post","link":"https:\/\/legendnilecruise.com\/de\/artikel\/tal-der-konige-teil-ii\/","title":{"rendered":"Tal der K\u00f6nige (Teil II)"},"content":{"rendered":"<div id=\"q-app\" data-v-app=\"\">\n<div class=\"q-layout q-layout--standard\" tabindex=\"-1\">\n<div class=\"q-layout q-layout--standard shadow-2 rounded-borders\" tabindex=\"-1\" data-v-047a0c4b=\"\">\n<div class=\"q-page-container bg-grey-2\" data-v-047a0c4b=\"\">\n<div class=\"q-layout q-layout--standard bg-white\" tabindex=\"-1\" data-v-16884332=\"\" data-v-047a0c4b=\"\">\n<article data-v-16884332=\"\">\n<section class=\"main-article\" data-v-16884332=\"\">\n<div class=\"article-part\" data-v-16884332=\"\">\n<h4 data-v-16884332=\"\"><strong>Das Grabmal des Tutanchamun<\/strong><\/h4>\n<p data-v-16884332=\"\">Die wichtigste arch\u00e4ologische Entdeckung in der Weltgeschichte war die Entdeckung des Grabes des jungen K\u00f6nigs Tutanchamun am 4. November 1922 durch den britischen Arch\u00e4ologen Howard Carter. Es ist bekannt, dass alle Gr\u00e4ber der \u00e4gyptischen K\u00f6nige, seien es die Pyramiden oder die K\u00f6nigsgr\u00e4ber im Tal der K\u00f6nige, ausgeraubt worden waren, so dass wir bis zur Entdeckung des Grabes von Tutanchamun kein vollst\u00e4ndiges K\u00f6nigsgrab gefunden haben. Carter fand nicht weniger als 5.000 kostbare Gold- und Steinsch\u00e4tze, von denen die ber\u00fchmte Maske von K\u00f6nig Tutanchamun der bekannteste ist. Hinzu kommen drei Sarkophage f\u00fcr den K\u00f6nig: Der erste ist aus Sandstein und sein Deckel ist aus Granit, und darin befindet sich der zweite Sarkophag. Der zweite Sarkophag ist aus vergoldetem Holz und in ihm befindet sich der dritte Sarkophag. Der dritte Sarkophag ist aus reinem Gold, und in ihm befanden sich die goldene Maske des K\u00f6nigs und die Mumie des K\u00f6nigs. Jeder Sarkophag war mit den vier Schutzg\u00f6ttinnen (Isis, Nephthys, Selket und Neith) geschm\u00fcckt.<\/p>\n<\/div>\n<div class=\"article-part\" data-v-16884332=\"\">\n<h4 data-v-16884332=\"\"><strong>Carter, der Entdecker des Grabes, und Lord Carnarvon, der Financier<\/strong><\/h4>\n<div class=\"q-img q-img--menu article-image\" role=\"img\" data-v-16884332=\"\">\n<div><\/div>\n<div class=\"q-img__container absolute-full\"><img fetchpriority=\"high\" decoding=\"async\" class=\"alignnone wp-image-13137\" src=\"https:\/\/legendnilecruise.com\/wp-content\/uploads\/2025\/03\/Carter-300x179.jpg\" alt=\"\" width=\"928\" height=\"554\" srcset=\"https:\/\/legendnilecruise.com\/wp-content\/uploads\/2025\/03\/Carter-300x179.jpg 300w, https:\/\/legendnilecruise.com\/wp-content\/uploads\/2025\/03\/Carter.jpg 500w\" sizes=\"(max-width: 928px) 100vw, 928px\" \/><\/div>\n<div class=\"q-img__content absolute-full q-anchor--skip\"><\/div>\n<\/div>\n<\/div>\n<div class=\"article-part\" data-v-16884332=\"\">\n<div class=\"q-img q-img--menu article-image\" role=\"img\" data-v-16884332=\"\">\n<div><\/div>\n<div class=\"q-img__container absolute-full\"><img decoding=\"async\" class=\"alignnone wp-image-13180\" src=\"https:\/\/legendnilecruise.com\/wp-content\/uploads\/2025\/03\/Carter_lvx7c2W-300x215.jpg\" alt=\"\" width=\"1091\" height=\"782\" srcset=\"https:\/\/legendnilecruise.com\/wp-content\/uploads\/2025\/03\/Carter_lvx7c2W-300x215.jpg 300w, https:\/\/legendnilecruise.com\/wp-content\/uploads\/2025\/03\/Carter_lvx7c2W.jpg 414w\" sizes=\"(max-width: 1091px) 100vw, 1091px\" \/><\/div>\n<div class=\"q-img__content absolute-full q-anchor--skip\"><\/div>\n<\/div>\n<\/div>\n<div class=\"article-part\" data-v-16884332=\"\">\n<h4 data-v-16884332=\"\"><strong>Der Grund f\u00fcr die vollst\u00e4ndige Entdeckung des Grabes<\/strong><\/h4>\n<p data-v-16884332=\"\">Beim Bau des gr\u00f6\u00dften Grabes im Tal der K\u00f6nige, des Grabes von Ramsis VI., gruben die Arbeiter und warfen den Schutt auf das kleine Grab von Tutanchamun, so dass der Eingang versperrt war und der Schutt das Grab vollst\u00e4ndig bedeckte. Dies hat uns geholfen, diese erstaunliche Entdeckung von Sch\u00e4tzen zu machen, die einem K\u00f6nig geh\u00f6rten, der nur 9 Jahre lang regierte und jung starb. Stellen Sie sich also vor, wir w\u00fcrden das Grab eines gro\u00dfen K\u00f6nigs wie Thutmose III. oder Ramses II. mit seinem gesamten Inhalt finden?<\/p>\n<\/div>\n<div class=\"article-part\" data-v-16884332=\"\">\n<h4 data-v-16884332=\"\"><strong>K\u00f6nig Tutanchamun<\/strong><\/h4>\n<p data-v-16884332=\"\">Nach dem Tod von Echnaton bestieg sein Sohn K\u00f6nig Tutanchamun im Alter von etwa 9 Jahren den Thron und wurde mit seiner Halbschwester Smenkhkare (Tochter von Echnaton und Nofretete) verheiratet. K\u00f6nig Tutanchamun regierte zun\u00e4chst von Tell el-Amarna (Akhetaten) aus, der Stadt seines Vaters Echnaton, doch die Priester in Theben \u00fcberzeugten ihn, nach Theben zur\u00fcckzukehren und von dort aus zu regieren. So kehrte er zur Religion des Amun zur\u00fcck und \u00e4nderte seinen Namen von Tutanchaten in Tutanchamun. Tutanchamun bedeutet \"das lebende Abbild des Gottes Amun\". Aufgrund seines jungen Alters war sein Wesir Ay derjenige, der mit ihm regierte. Tutanchamun ging gerne in seinem Wagen auf die Jagd, und einmal st\u00fcrzte der Wagen um und er brach sich ein Bein, so dass er begann, mit einem Stock zu gehen. Aus diesem Grund fand man in seinem Grab viele St\u00f6cke. Nachdem Wissenschaftler vor kurzem (zwischen 2022 und 2024) DNA-Tests durchgef\u00fchrt hatten, fanden sie heraus, dass der K\u00f6nig an etwas \u00e4hnlichem wie Malaria litt. Deshalb glaubt Dr. Zahi Hawass, dass er an dieser Krankheit starb, was das Vorhandensein vieler K\u00f6rner im Grab erkl\u00e4rt, von denen das ber\u00fchmteste Bockshornklee ist, da es diese Krankheit behandelt. Als die Leiche entdeckt wurde, fand man ein Loch in seinem Kopf. Einige glauben, dass es sich um eine Axt handelte, mit der er ermordet wurde, w\u00e4hrend andere glauben, dass dies w\u00e4hrend des Mumifizierungsprozesses geschah. Da der K\u00f6nig in jungen Jahren regierte und jung starb (er regierte im Alter von neun Jahren und starb im Alter von 18 Jahren), wird angenommen, dass dieses Grab urspr\u00fcnglich f\u00fcr seinen Wesir Ay bestimmt war (der sp\u00e4ter in einem anderen Grab bestattet wurde). Der K\u00f6nig wurde also in dieser kleinen Kammer begraben, und wir finden darin, dass Ay die Krone als K\u00f6nig nach Tutanchamun tr\u00e4gt und ein Leopardenfell tr\u00e4gt (als Hohepriester) und das Ritual der Mund\u00f6ffnung f\u00fcr K\u00f6nig Tutanchamun durchf\u00fchrt. Die Grabausstattungen wurden mit dem K\u00f6nig und allem, was er im Jenseits brauchte, begraben, sogar Betten und Sandalen, die alle aus Gold oder vergoldet waren, was auf den Reichtum hinweist, der \u00c4gypten in dieser Zeit auszeichnete. Die meisten Sch\u00e4tze des Grabes wurden in das \u00c4gyptische Museum am Tahrir-Platz in Kairo gebracht und werden dieses Jahr (2024) in das Gro\u00dfe \u00c4gyptische Museum in der N\u00e4he der Pyramiden \u00fcberf\u00fchrt. Carter nahm auch viele Artefakte mit und brachte sie nach Gro\u00dfbritannien, und einige wurden verkauft und befinden sich jetzt in einigen internationalen Museen.<\/p>\n<\/div>\n<div class=\"article-part\" data-v-16884332=\"\">\n<h4 data-v-16884332=\"\"><strong>Wichtige Bilder von Tutanchamuns Grabmal<\/strong><\/h4>\n<\/div>\n<div class=\"article-part\" data-v-16884332=\"\">\n<h4 data-v-16884332=\"\"><strong>Tutanchamuns Kammer war bei der Entdeckung des Grabes geschlossen<\/strong><\/h4>\n<div class=\"q-img q-img--menu article-image\" role=\"img\" data-v-16884332=\"\">\n<div><\/div>\n<div class=\"q-img__container absolute-full\"><img decoding=\"async\" class=\"alignnone wp-image-13179\" src=\"https:\/\/legendnilecruise.com\/wp-content\/uploads\/2025\/03\/Tutankhamuns-293x300.jpg\" alt=\"\" width=\"1084\" height=\"1110\" srcset=\"https:\/\/legendnilecruise.com\/wp-content\/uploads\/2025\/03\/Tutankhamuns-293x300.jpg 293w, https:\/\/legendnilecruise.com\/wp-content\/uploads\/2025\/03\/Tutankhamuns.jpg 308w\" sizes=\"(max-width: 1084px) 100vw, 1084px\" \/><\/div>\n<div class=\"q-img__content absolute-full q-anchor--skip\"><\/div>\n<\/div>\n<\/div>\n<div class=\"article-part\" data-v-16884332=\"\">\n<h4 data-v-16884332=\"\"><strong>Bild aus dem Jahr 1922, als das Grabmal entdeckt wurde<\/strong><\/h4>\n<div class=\"q-img q-img--menu article-image\" role=\"img\" data-v-16884332=\"\">\n<div><\/div>\n<div class=\"q-img__container absolute-full\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-13178\" src=\"https:\/\/legendnilecruise.com\/wp-content\/uploads\/2025\/03\/Tutankhamuns_2-300x280.jpg\" alt=\"\" width=\"1085\" height=\"1013\" srcset=\"https:\/\/legendnilecruise.com\/wp-content\/uploads\/2025\/03\/Tutankhamuns_2-300x280.jpg 300w, https:\/\/legendnilecruise.com\/wp-content\/uploads\/2025\/03\/Tutankhamuns_2.jpg 322w\" sizes=\"(max-width: 1085px) 100vw, 1085px\" \/><\/div>\n<div class=\"q-img__content absolute-full q-anchor--skip\"><\/div>\n<\/div>\n<\/div>\n<div class=\"article-part\" data-v-16884332=\"\">\n<h4 data-v-16884332=\"\"><strong>Erstes Bild der Entdeckung des Inneren des Grabes<\/strong><\/h4>\n<div class=\"q-img q-img--menu article-image\" role=\"img\" data-v-16884332=\"\">\n<div><\/div>\n<div class=\"q-img__container absolute-full\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-13177\" src=\"https:\/\/legendnilecruise.com\/wp-content\/uploads\/2025\/03\/image-248x300.jpg\" alt=\"\" width=\"920\" height=\"1113\" srcset=\"https:\/\/legendnilecruise.com\/wp-content\/uploads\/2025\/03\/image-248x300.jpg 248w, https:\/\/legendnilecruise.com\/wp-content\/uploads\/2025\/03\/image.jpg 310w\" sizes=\"(max-width: 920px) 100vw, 920px\" \/><\/div>\n<div class=\"q-img__content absolute-full q-anchor--skip\"><\/div>\n<\/div>\n<\/div>\n<div class=\"article-part\" data-v-16884332=\"\">\n<h4 data-v-16884332=\"\"><strong>Grabkammer von K\u00f6nig Tutanchamun<\/strong><\/h4>\n<div class=\"q-img q-img--menu article-image\" role=\"img\" data-v-16884332=\"\">\n<div><\/div>\n<div class=\"q-img__container absolute-full\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-13176\" src=\"https:\/\/legendnilecruise.com\/wp-content\/uploads\/2025\/03\/chamber_d09KLWE-300x190.png\" alt=\"\" width=\"1284\" height=\"813\" srcset=\"https:\/\/legendnilecruise.com\/wp-content\/uploads\/2025\/03\/chamber_d09KLWE-300x190.png 300w, https:\/\/legendnilecruise.com\/wp-content\/uploads\/2025\/03\/chamber_d09KLWE-768x486.png 768w, https:\/\/legendnilecruise.com\/wp-content\/uploads\/2025\/03\/chamber_d09KLWE-820x520.png 820w, https:\/\/legendnilecruise.com\/wp-content\/uploads\/2025\/03\/chamber_d09KLWE-711x450.png 711w, https:\/\/legendnilecruise.com\/wp-content\/uploads\/2025\/03\/chamber_d09KLWE.png 875w\" sizes=\"(max-width: 1284px) 100vw, 1284px\" \/><\/div>\n<div class=\"q-img__content absolute-full q-anchor--skip\"><\/div>\n<\/div>\n<\/div>\n<div class=\"article-part\" data-v-16884332=\"\">\n<h4 data-v-16884332=\"\"><strong>Mumie von K\u00f6nig Tutanchamun in seinem Grab im Tal der K\u00f6nige auf der Westbank von Luxor<\/strong><\/h4>\n<div class=\"q-img q-img--menu article-image\" role=\"img\" data-v-16884332=\"\">\n<div><\/div>\n<div class=\"q-img__container absolute-full\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-13175\" src=\"https:\/\/legendnilecruise.com\/wp-content\/uploads\/2025\/03\/mummy.jpg\" alt=\"\" width=\"883\" height=\"1080\" \/><\/div>\n<div class=\"q-img__content absolute-full q-anchor--skip\"><\/div>\n<\/div>\n<\/div>\n<div class=\"article-part\" data-v-16884332=\"\">\n<p data-v-16884332=\"\">Szene des Rituals der Mund\u00f6ffnung: K\u00f6nig Ay mit Leopardenfell bei der \u00d6ffnung des Mundes f\u00fcr die Mumie des K\u00f6nigs, in der Mitte ein junger K\u00f6nig mit seiner Frau<\/p>\n<div class=\"q-img q-img--menu article-image\" role=\"img\" data-v-16884332=\"\">\n<div><\/div>\n<div class=\"q-img__container absolute-full\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-13174\" src=\"https:\/\/legendnilecruise.com\/wp-content\/uploads\/2025\/03\/SCENE-300x130.png\" alt=\"\" width=\"854\" height=\"370\" srcset=\"https:\/\/legendnilecruise.com\/wp-content\/uploads\/2025\/03\/SCENE-300x130.png 300w, https:\/\/legendnilecruise.com\/wp-content\/uploads\/2025\/03\/SCENE-768x332.png 768w, https:\/\/legendnilecruise.com\/wp-content\/uploads\/2025\/03\/SCENE.png 883w\" sizes=\"(max-width: 854px) 100vw, 854px\" \/><\/div>\n<div class=\"q-img__content absolute-full q-anchor--skip\"><\/div>\n<\/div>\n<\/div>\n<div class=\"article-part\" data-v-16884332=\"\">\n<h4 data-v-16884332=\"\"><strong>K\u00f6nig Tut und sein Ka oder Ba, und er umarmt Osiris<\/strong><\/h4>\n<div class=\"q-img q-img--menu article-image\" role=\"img\" data-v-16884332=\"\">\n<div><\/div>\n<div class=\"q-img__container absolute-full\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-13172\" src=\"https:\/\/legendnilecruise.com\/wp-content\/uploads\/2025\/03\/tut-239x300.png\" alt=\"\" width=\"1088\" height=\"1366\" srcset=\"https:\/\/legendnilecruise.com\/wp-content\/uploads\/2025\/03\/tut-239x300.png 239w, https:\/\/legendnilecruise.com\/wp-content\/uploads\/2025\/03\/tut-358x450.png 358w, https:\/\/legendnilecruise.com\/wp-content\/uploads\/2025\/03\/tut.png 550w\" sizes=\"(max-width: 1088px) 100vw, 1088px\" \/><\/div>\n<div class=\"q-img__content absolute-full q-anchor--skip\"><\/div>\n<\/div>\n<\/div>\n<div class=\"article-part\" data-v-16884332=\"\">\n<h4 data-v-16884332=\"\"><strong>Leichenzug<\/strong><\/h4>\n<div class=\"q-img q-img--menu article-image\" role=\"img\" data-v-16884332=\"\">\n<div><\/div>\n<div class=\"q-img__container absolute-full\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-13171\" src=\"https:\/\/legendnilecruise.com\/wp-content\/uploads\/2025\/03\/Funeral_procession-300x168.jpg\" alt=\"\" width=\"1075\" height=\"602\" srcset=\"https:\/\/legendnilecruise.com\/wp-content\/uploads\/2025\/03\/Funeral_procession-300x168.jpg 300w, https:\/\/legendnilecruise.com\/wp-content\/uploads\/2025\/03\/Funeral_procession-1024x574.jpg 1024w, https:\/\/legendnilecruise.com\/wp-content\/uploads\/2025\/03\/Funeral_procession-768x431.jpg 768w, https:\/\/legendnilecruise.com\/wp-content\/uploads\/2025\/03\/Funeral_procession-802x450.jpg 802w, https:\/\/legendnilecruise.com\/wp-content\/uploads\/2025\/03\/Funeral_procession.jpg 1148w\" sizes=\"(max-width: 1075px) 100vw, 1075px\" \/><\/div>\n<div class=\"q-img__content absolute-full q-anchor--skip\"><\/div>\n<\/div>\n<\/div>\n<div class=\"article-part\" data-v-16884332=\"\">\n<h4 data-v-16884332=\"\"><strong>12 Affen, die die zw\u00f6lf Stunden der Nacht darstellen, Details aus der ersten Stunde des Buches Amduat<\/strong><\/h4>\n<div class=\"q-img q-img--menu article-image\" role=\"img\" data-v-16884332=\"\">\n<div><\/div>\n<div class=\"q-img__container absolute-full\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-13170\" src=\"https:\/\/legendnilecruise.com\/wp-content\/uploads\/2025\/03\/monkeys-300x200.png\" alt=\"\" width=\"833\" height=\"555\" srcset=\"https:\/\/legendnilecruise.com\/wp-content\/uploads\/2025\/03\/monkeys-300x200.png 300w, https:\/\/legendnilecruise.com\/wp-content\/uploads\/2025\/03\/monkeys-675x450.png 675w, https:\/\/legendnilecruise.com\/wp-content\/uploads\/2025\/03\/monkeys.png 713w\" sizes=\"(max-width: 833px) 100vw, 833px\" \/><\/div>\n<div class=\"q-img__content absolute-full q-anchor--skip\"><\/div>\n<\/div>\n<\/div>\n<div class=\"article-part\" data-v-16884332=\"\">\n<h4 data-v-16884332=\"\"><strong>K\u00f6nig Tutanchamun mit Anubis im Hintergrund Einige Sch\u00e4tze aus dem Grab des Tutanchamun<\/strong><\/h4>\n<div class=\"q-img q-img--menu article-image\" role=\"img\" data-v-16884332=\"\">\n<div><\/div>\n<div class=\"q-img__container absolute-full\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-13169\" src=\"https:\/\/legendnilecruise.com\/wp-content\/uploads\/2025\/03\/tut2-234x300.jpg\" alt=\"\" width=\"880\" height=\"1128\" srcset=\"https:\/\/legendnilecruise.com\/wp-content\/uploads\/2025\/03\/tut2-234x300.jpg 234w, https:\/\/legendnilecruise.com\/wp-content\/uploads\/2025\/03\/tut2-351x450.jpg 351w, https:\/\/legendnilecruise.com\/wp-content\/uploads\/2025\/03\/tut2.jpg 673w\" sizes=\"(max-width: 880px) 100vw, 880px\" \/><\/div>\n<div class=\"q-img__content absolute-full q-anchor--skip\"><\/div>\n<\/div>\n<\/div>\n<div class=\"article-part\" data-v-16884332=\"\">\n<h4 data-v-16884332=\"\"><strong>Die Maske des Tutanchamun<\/strong><\/h4>\n<div class=\"q-img q-img--menu article-image\" role=\"img\" data-v-16884332=\"\">\n<div><\/div>\n<div class=\"q-img__container absolute-full\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-13168\" src=\"https:\/\/legendnilecruise.com\/wp-content\/uploads\/2025\/03\/mask-244x300.jpg\" alt=\"\" width=\"1087\" height=\"1336\" srcset=\"https:\/\/legendnilecruise.com\/wp-content\/uploads\/2025\/03\/mask-244x300.jpg 244w, https:\/\/legendnilecruise.com\/wp-content\/uploads\/2025\/03\/mask.jpg 261w\" sizes=\"(max-width: 1087px) 100vw, 1087px\" \/><\/div>\n<div class=\"q-img__content absolute-full q-anchor--skip\"><\/div>\n<\/div>\n<\/div>\n<div class=\"article-part\" data-v-16884332=\"\">\n<h4 data-v-16884332=\"\"><strong>Brustpanzer von K\u00f6nig Tutanchamun<\/strong><\/h4>\n<div class=\"q-img q-img--menu article-image\" role=\"img\" data-v-16884332=\"\">\n<div><\/div>\n<div class=\"q-img__container absolute-full\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-13167\" src=\"https:\/\/legendnilecruise.com\/wp-content\/uploads\/2025\/03\/tut3.jpg\" alt=\"\" width=\"812\" height=\"738\" \/><\/div>\n<div class=\"q-img__content absolute-full q-anchor--skip\"><\/div>\n<\/div>\n<\/div>\n<div class=\"article-part\" data-v-16884332=\"\">\n<h4 data-v-16884332=\"\"><strong>Der K\u00f6nig jagt mit einem Speer in seinem goldenen Wagen<\/strong><\/h4>\n<div class=\"q-img q-img--menu article-image\" role=\"img\" data-v-16884332=\"\">\n<div><\/div>\n<div class=\"q-img__container absolute-full\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-13166\" src=\"https:\/\/legendnilecruise.com\/wp-content\/uploads\/2025\/03\/tut4-243x300.jpg\" alt=\"\" width=\"1013\" height=\"1251\" srcset=\"https:\/\/legendnilecruise.com\/wp-content\/uploads\/2025\/03\/tut4-243x300.jpg 243w, https:\/\/legendnilecruise.com\/wp-content\/uploads\/2025\/03\/tut4.jpg 296w\" sizes=\"(max-width: 1013px) 100vw, 1013px\" \/><\/div>\n<div class=\"q-img__content absolute-full q-anchor--skip\"><\/div>\n<\/div>\n<\/div>\n<div class=\"article-part\" data-v-16884332=\"\">\n<h4 data-v-16884332=\"\"><strong>Sandalen des K\u00f6nigs Tutanchamun aus Gold<\/strong><\/h4>\n<div class=\"q-img q-img--menu article-image\" role=\"img\" data-v-16884332=\"\">\n<div><\/div>\n<div class=\"q-img__container absolute-full\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-13203\" src=\"https:\/\/legendnilecruise.com\/wp-content\/uploads\/2025\/03\/sandels-300x233.jpg\" alt=\"\" width=\"890\" height=\"691\" srcset=\"https:\/\/legendnilecruise.com\/wp-content\/uploads\/2025\/03\/sandels-300x233.jpg 300w, https:\/\/legendnilecruise.com\/wp-content\/uploads\/2025\/03\/sandels.jpg 451w\" sizes=\"(max-width: 890px) 100vw, 890px\" \/><\/div>\n<div class=\"q-img__content absolute-full q-anchor--skip\"><\/div>\n<\/div>\n<\/div>\n<div class=\"article-part\" data-v-16884332=\"\">\n<h4 data-v-16884332=\"\"><strong>Kosmetikbox von K\u00f6nig Tutanchamun<\/strong><\/h4>\n<div class=\"q-img q-img--menu article-image\" role=\"img\" data-v-16884332=\"\">\n<div><\/div>\n<div class=\"q-img__container absolute-full\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-13165\" src=\"https:\/\/legendnilecruise.com\/wp-content\/uploads\/2025\/03\/box-214x300.jpg\" alt=\"\" width=\"753\" height=\"1056\" srcset=\"https:\/\/legendnilecruise.com\/wp-content\/uploads\/2025\/03\/box-214x300.jpg 214w, https:\/\/legendnilecruise.com\/wp-content\/uploads\/2025\/03\/box.jpg 270w\" sizes=\"(max-width: 753px) 100vw, 753px\" \/><\/div>\n<div class=\"q-img__content absolute-full q-anchor--skip\"><\/div>\n<\/div>\n<\/div>\n<div class=\"article-part\" data-v-16884332=\"\">\n<h4 data-v-16884332=\"\"><strong>Ramses VI (etwa 1443-1136 v. Chr.)<\/strong><\/h4>\n<p data-v-16884332=\"\">Ramses VI. war einer der S\u00f6hne von Ramses III. Er folgte seinem Neffen Ramses V. auf den Thron und regierte acht Jahre lang. Er beauftragte die Arbeiter von Deir el-Medina mit der Fertigstellung des Grabes von Ramses V., das er usurpiert hatte, und baute eines der sch\u00f6nsten Gr\u00e4ber im Tal der K\u00f6nige, 93 Meter tief. Er erweiterte das Grab und nutzte es f\u00fcr seine Bestattung. Der Grundriss des Grabes war einfach, es bestand aus einer Gruppe von absteigenden G\u00e4ngen, die in einer geraden Linie zu der tief unter der Erde liegenden Grabkammer f\u00fchrten, und seine Inschriften waren gut erhalten.<\/p>\n<\/div>\n<div class=\"article-part\" data-v-16884332=\"\">\n<h4 data-v-16884332=\"\"><strong>Namen des Grabes<\/strong><\/h4>\n<p data-v-16884332=\"\">Die franz\u00f6sische Expedition nannte es das \"Grab der verk\u00f6rperten Seele\". Die Engl\u00e4nder nannten es \"Tomb of Memnon\" (wegen der \u00c4hnlichkeit des Kr\u00f6nungsnamens von K\u00f6nig Ramses VI. mit dem Kr\u00f6nungsnamen von K\u00f6nig Amenhotep III, dem Besitzer der Memnon-Kolosse). Es wurde \"Doppelgrab\" genannt, weil die Grabkammer mit einer kleinen Kammer abschlie\u00dft, so dass man es als zwei Grabkammern betrachtete.<\/p>\n<\/div>\n<div class=\"article-part\" data-v-16884332=\"\">\n<h4 data-v-16884332=\"\"><strong>Beschreibung des Grabes von Ramses VI (KV9)<\/strong><\/h4>\n<p data-v-16884332=\"\">Auf dem T\u00fcrsturz \u00fcber dem Eingang sehen wir eine Szene, die die Sonnenscheibe (Ra) mit Khepri (dem Skarab\u00e4us) darin und dann Atum mit einem Widderkopf darstellt, der die Sonne in der Morgend\u00e4mmerung, am Mittag und in der Abendd\u00e4mmerung repr\u00e4sentiert. Auf den Schultern der T\u00fcr sind die Namen von K\u00f6nig Ramses VI. in Kartuschen eingraviert. Die Szenen des Grabes enthalten zahlreiche Grabinschriften, die dem K\u00f6nig einen friedlichen \u00dcbergang ins Jenseits erm\u00f6glichen. Der erste absteigende Korridor war mit dem Buch der Tore, dem Buch der H\u00f6hlen und dem Buch des Himmels geschm\u00fcckt. Die folgenden Korridore waren mit Szenen aus dem Buch des Amduat (das bedeutet \"das, was in der Unterwelt ist\"), dem Buch der Toten und dem Buch des Himmels geschm\u00fcckt. Die Grabkammer war mit Szenen aus dem Buch der Erde geschm\u00fcckt. Die Decken waren mit astronomischen Szenen und Inschriften geschm\u00fcckt. Bei einigen dieser Grabspr\u00fcche handelt es sich um eine Sammlung von Zauberspr\u00fcchen, bei anderen um Karten der Unterwelt, in denen die t\u00e4gliche n\u00e4chtliche Reise des Sonnengottes durch die Unterwelt beschrieben wird, die es dem K\u00f6nig erm\u00f6glicht, seine Wiedergeburt am \u00f6stlichen Horizont im Morgengrauen wie der Sonnengott sicherzustellen.<\/p>\n<\/div>\n<div class=\"article-part\" data-v-16884332=\"\">\n<h4 data-v-16884332=\"\"><strong>Szene mit den Namen von K\u00f6nig Ramses VI. in Kartuschen auf dem T\u00fcrsturz am Eingang des Grabes<\/strong><\/h4>\n<div class=\"q-img q-img--menu article-image\" role=\"img\" data-v-16884332=\"\">\n<div><\/div>\n<div class=\"q-img__container absolute-full\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-13164\" src=\"https:\/\/legendnilecruise.com\/wp-content\/uploads\/2025\/03\/rameses_vi-169x300.jpg\" alt=\"\" width=\"832\" height=\"1477\" srcset=\"https:\/\/legendnilecruise.com\/wp-content\/uploads\/2025\/03\/rameses_vi-169x300.jpg 169w, https:\/\/legendnilecruise.com\/wp-content\/uploads\/2025\/03\/rameses_vi-253x450.jpg 253w, https:\/\/legendnilecruise.com\/wp-content\/uploads\/2025\/03\/rameses_vi.jpg 265w\" sizes=\"(max-width: 832px) 100vw, 832px\" \/><\/div>\n<div class=\"q-img__content absolute-full q-anchor--skip\"><\/div>\n<\/div>\n<\/div>\n<div class=\"article-part\" data-v-16884332=\"\">\n<h4 data-v-16884332=\"\"><strong>Der erste Korridor<\/strong><\/h4>\n<p data-v-16884332=\"\">Auf der linken Seite des Eingangs sehen wir eine Szene des K\u00f6nigs vor verschiedenen Gottheiten, gefolgt von Texten und Szenen aus dem ersten und zweiten Kapitel des Buches der Tore. Auf der rechten Seite sehen wir eine Szene, in der der K\u00f6nig dem Gott Weihrauch opfert, um die b\u00f6sen Geister aus seinem Grab zu vertreiben. Dann folgen Szenen aus dem Buch der H\u00f6hlen, die durch ovale Formen gekennzeichnet sind, die S\u00e4rge mit G\u00f6ttern und Toten darstellen.<\/p>\n<\/div>\n<div class=\"article-part\" data-v-16884332=\"\">\n<h4 data-v-16884332=\"\"><strong>Der zweite Korridor<\/strong><\/h4>\n<p data-v-16884332=\"\">Auf dem \u00e4u\u00dferen T\u00fcrsturz des Korridors sehen wir die gefl\u00fcgelte Sonnenscheibe. Auf der linken Seite sind Kapitel aus dem Buch der Pforten zu sehen, und das sch\u00f6nste ist das vierte Kapitel des Buches der Pforten, in dem die Halle des Osiris zu sehen ist (die Szene, von der die Franzosen glaubten, sie stelle die Seelenwanderung dar). Auf der rechten Seite des Korridors befinden sich Szenen aus dem zweiten und dritten Kapitel des Buches der H\u00f6hlen.<\/p>\n<\/div>\n<div class=\"article-part\" data-v-16884332=\"\">\n<h4 data-v-16884332=\"\"><strong>Der dritte Korridor<\/strong><\/h4>\n<p data-v-16884332=\"\">Das gleiche Muster findet sich auf der linken Seite im Buch der Tore und auf der rechten Seite im Buch der H\u00f6hlen.<\/p>\n<\/div>\n<div class=\"article-part\" data-v-16884332=\"\">\n<h4 data-v-16884332=\"\"><strong>Der innere Korridor des Grabes<\/strong><\/h4>\n<div class=\"q-img q-img--menu article-image\" role=\"img\" data-v-16884332=\"\">\n<div><\/div>\n<div class=\"q-img__container absolute-full\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-13163\" src=\"https:\/\/legendnilecruise.com\/wp-content\/uploads\/2025\/03\/The_Inner_Corridor_of_the_Tomb-300x200.jpg\" alt=\"\" width=\"1064\" height=\"709\" srcset=\"https:\/\/legendnilecruise.com\/wp-content\/uploads\/2025\/03\/The_Inner_Corridor_of_the_Tomb-300x200.jpg 300w, https:\/\/legendnilecruise.com\/wp-content\/uploads\/2025\/03\/The_Inner_Corridor_of_the_Tomb-768x511.jpg 768w, https:\/\/legendnilecruise.com\/wp-content\/uploads\/2025\/03\/The_Inner_Corridor_of_the_Tomb-676x450.jpg 676w, https:\/\/legendnilecruise.com\/wp-content\/uploads\/2025\/03\/The_Inner_Corridor_of_the_Tomb.jpg 964w\" sizes=\"(max-width: 1064px) 100vw, 1064px\" \/><\/div>\n<div class=\"q-img__content absolute-full q-anchor--skip\"><\/div>\n<\/div>\n<\/div>\n<div class=\"article-part\" data-v-16884332=\"\">\n<h4 data-v-16884332=\"\"><strong>Eine Szene, in der der K\u00f6nig dem Gott Ra-Hor akhty Opfergaben darbringt<\/strong><\/h4>\n<div class=\"q-img q-img--menu article-image\" role=\"img\" data-v-16884332=\"\">\n<div><\/div>\n<div class=\"q-img__container absolute-full\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-13162\" src=\"https:\/\/legendnilecruise.com\/wp-content\/uploads\/2025\/03\/king2-225x300.jpg\" alt=\"\" width=\"1089\" height=\"1452\" srcset=\"https:\/\/legendnilecruise.com\/wp-content\/uploads\/2025\/03\/king2-225x300.jpg 225w, https:\/\/legendnilecruise.com\/wp-content\/uploads\/2025\/03\/king2.jpg 294w\" sizes=\"(max-width: 1089px) 100vw, 1089px\" \/><\/div>\n<div class=\"q-img__content absolute-full q-anchor--skip\"><\/div>\n<\/div>\n<\/div>\n<div class=\"article-part\" data-v-16884332=\"\">\n<h4 data-v-16884332=\"\"><strong>Eine Szene, in der Boote in der Unterwelt gezogen werden, vor denen Reihen von G\u00f6ttern stehen, die Messer tragen, um den Kopf der Schlange Apophis abzuschlagen<\/strong><\/h4>\n<div class=\"q-img q-img--menu article-image\" role=\"img\" data-v-16884332=\"\">\n<div><\/div>\n<div class=\"q-img__container absolute-full\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-13161\" src=\"https:\/\/legendnilecruise.com\/wp-content\/uploads\/2025\/03\/pulling-300x260.jpg\" alt=\"\" width=\"863\" height=\"748\" srcset=\"https:\/\/legendnilecruise.com\/wp-content\/uploads\/2025\/03\/pulling-300x260.jpg 300w, https:\/\/legendnilecruise.com\/wp-content\/uploads\/2025\/03\/pulling.jpg 340w\" sizes=\"(max-width: 863px) 100vw, 863px\" \/><\/div>\n<div class=\"q-img__content absolute-full q-anchor--skip\"><\/div>\n<\/div>\n<\/div>\n<div class=\"article-part\" data-v-16884332=\"\">\n<h4 data-v-16884332=\"\"><strong>Eine Szene aus dem dritten Korridor aus dem Buch der H\u00f6hlen<\/strong><\/h4>\n<div class=\"q-img q-img--menu article-image\" role=\"img\" data-v-16884332=\"\">\n<div><\/div>\n<div class=\"q-img__container absolute-full\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-13160\" src=\"https:\/\/legendnilecruise.com\/wp-content\/uploads\/2025\/03\/scene2-225x300.jpg\" alt=\"\" width=\"1061\" height=\"1415\" srcset=\"https:\/\/legendnilecruise.com\/wp-content\/uploads\/2025\/03\/scene2-225x300.jpg 225w, https:\/\/legendnilecruise.com\/wp-content\/uploads\/2025\/03\/scene2.jpg 300w\" sizes=\"(max-width: 1061px) 100vw, 1061px\" \/><\/div>\n<div class=\"q-img__content absolute-full q-anchor--skip\"><\/div>\n<\/div>\n<\/div>\n<div class=\"article-part\" data-v-16884332=\"\">\n<h4 data-v-16884332=\"\"><strong>Die Decke des Grabes<\/strong><\/h4>\n<p data-v-16884332=\"\">Das Grab von Ramses VI. ist mit seinen charakteristischen Deckenszenen einzigartig und aufgrund der astronomischen Tabellen und ihrer Symbole sowie der vollst\u00e4ndigen Darstellung der B\u00fccher der Nacht und des Tages von gro\u00dfer Bedeutung, da dieses Buch nur in diesem Grab abgebildet war. An der Decke des Grabes waren viele wichtige Sternbilder abgebildet. Da die alten \u00c4gypter glaubten, dass die Himmelsg\u00f6ttin Nut die Sonne am Morgen gebar und sie in der Nacht verschluckte, reiste die Sonne tags\u00fcber in ihrem Boot auf dem K\u00f6rper von Nut, und nachts wurde das Boot der Sonne von einer Gruppe von Gottheiten, den unerm\u00fcdlichen Sternen, im K\u00f6rper der Himmelsg\u00f6ttin gezogen. Das Buch des Tages erscheint auf der \u00f6stlichen Seite und stellt die Szene der Geburt der neuen Sonne aus dem Scho\u00df von Nut mit einer leuchtend gelben Farbe und blauen Sternen dar, und die rote Sonnenscheibe wird von dem gefl\u00fcgelten Skarab\u00e4us getragen, und unter dem gefl\u00fcgelten Skarab\u00e4us erscheint eine G\u00f6ttin in der Form einer schwangeren Frau, die die Sonnenscheibe tr\u00e4gt, kniend in einer frontalen Position zwischen Isis und Nephthys, die in einer seitlichen Position sitzen, und im Inneren der Scheibe erscheint ein kleines Kind in gro\u00dfem Detail. Und in der ersten Stunde erscheinen die G\u00f6ttinnen Isis, Nephthys und Nut, unterst\u00fctzt vom Gott Shu, der auf einem gro\u00dfen Boot mit gebogenem Heck stehend erscheint, begleitet von sechs G\u00f6ttinnen. Und wir sehen den Fluss in Form eines Trapezes in einer hellblauen Farbe dargestellt, und in seinem Inneren befinden sich zwei Boote f\u00fcr Tag und Nacht.<\/p>\n<\/div>\n<div class=\"article-part\" data-v-16884332=\"\">\n<h4 data-v-16884332=\"\"><strong>Schauplatz der astronomischen Tafeln<\/strong><\/h4>\n<div class=\"q-img q-img--menu article-image\" role=\"img\" data-v-16884332=\"\">\n<div><\/div>\n<div class=\"q-img__container absolute-full\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-13159\" src=\"https:\/\/legendnilecruise.com\/wp-content\/uploads\/2025\/03\/astronomical_tables-300x143.png\" alt=\"\" width=\"1089\" height=\"519\" srcset=\"https:\/\/legendnilecruise.com\/wp-content\/uploads\/2025\/03\/astronomical_tables-300x143.png 300w, https:\/\/legendnilecruise.com\/wp-content\/uploads\/2025\/03\/astronomical_tables.png 657w\" sizes=\"(max-width: 1089px) 100vw, 1089px\" \/><\/div>\n<div class=\"q-img__content absolute-full q-anchor--skip\"><\/div>\n<\/div>\n<\/div>\n<div class=\"article-part\" data-v-16884332=\"\">\n<h4 data-v-16884332=\"\"><strong>Szenen der Grabdecke mit der Darstellung des Buches des Tages<\/strong><\/h4>\n<div class=\"q-img q-img--menu article-image\" role=\"img\" data-v-16884332=\"\">\n<div><\/div>\n<div class=\"q-img__container absolute-full\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-13196\" src=\"https:\/\/legendnilecruise.com\/wp-content\/uploads\/2025\/03\/depicted-300x234.jpg\" alt=\"\" width=\"809\" height=\"631\" srcset=\"https:\/\/legendnilecruise.com\/wp-content\/uploads\/2025\/03\/depicted-300x234.jpg 300w, https:\/\/legendnilecruise.com\/wp-content\/uploads\/2025\/03\/depicted-768x600.jpg 768w, https:\/\/legendnilecruise.com\/wp-content\/uploads\/2025\/03\/depicted-576x450.jpg 576w, https:\/\/legendnilecruise.com\/wp-content\/uploads\/2025\/03\/depicted.jpg 988w\" sizes=\"(max-width: 809px) 100vw, 809px\" \/><\/div>\n<div class=\"q-img__content absolute-full q-anchor--skip\"><\/div>\n<\/div>\n<\/div>\n<div class=\"article-part\" data-v-16884332=\"\">\n<h4 data-v-16884332=\"\"><strong>Die Decke ist mit einem Geier (der G\u00f6ttin Nekhbet) verziert<\/strong><\/h4>\n<div class=\"q-img q-img--menu article-image\" role=\"img\" data-v-16884332=\"\">\n<div><\/div>\n<div class=\"q-img__container absolute-full\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-13158\" src=\"https:\/\/legendnilecruise.com\/wp-content\/uploads\/2025\/03\/ceiling-300x213.png\" alt=\"\" width=\"1030\" height=\"731\" srcset=\"https:\/\/legendnilecruise.com\/wp-content\/uploads\/2025\/03\/ceiling-300x213.png 300w, https:\/\/legendnilecruise.com\/wp-content\/uploads\/2025\/03\/ceiling-635x450.png 635w, https:\/\/legendnilecruise.com\/wp-content\/uploads\/2025\/03\/ceiling.png 752w\" sizes=\"(max-width: 1030px) 100vw, 1030px\" \/><\/div>\n<div class=\"q-img__content absolute-full q-anchor--skip\"><\/div>\n<\/div>\n<\/div>\n<div class=\"article-part\" data-v-16884332=\"\">\n<h4 data-v-16884332=\"\"><strong>Die Brunnenkammer<\/strong><\/h4>\n<p data-v-16884332=\"\">Auf der linken Seite befindet sich das Buch der Tore und auf der rechten Seite das Buch der H\u00f6hlen.<\/p>\n<\/div>\n<div class=\"article-part\" data-v-16884332=\"\">\n<h4 data-v-16884332=\"\"><strong>Die Halle der vier S\u00e4ulen<\/strong><\/h4>\n<p data-v-16884332=\"\">Auf den S\u00e4ulen sind Szenen des K\u00f6nigs mit den G\u00f6ttern zu sehen. An den W\u00e4nden des Saals befindet sich links das Buch der Tore und die ber\u00fchmte Szene, die den Gott Nun in Gestalt eines Mannes darstellt, der aus dem Urwasser aufsteigt und das Sonnenboot anhebt, in dem sich der Gott Khepri (der Skarab\u00e4us) befindet, als Symbol f\u00fcr die Geburt eines neuen Tages f\u00fcr die Sonne (dies weist auf die Wiedergeburt und das neue Leben des Verstorbenen hin). Au\u00dferdem finden wir die G\u00f6tter als Seeleute, Isis und Nephthys in Form von Schlangen und \u00fcber dem Kopf von Osiris die G\u00f6ttin Nut, die die aufgehende Sonne empf\u00e4ngt. Auf beiden Seiten des Korridors zwischen den S\u00e4ulen in der Halle sehen wir eine Szene mit der G\u00f6ttin Nekhbet, und unter ihr die G\u00f6ttin Neith in Form einer Schlange. Auf der rechten Seite sehen wir die G\u00f6ttinnen Meretseger und Selket, die G\u00f6ttinnen des Todes.<\/p>\n<\/div>\n<div class=\"article-part\" data-v-16884332=\"\">\n<h4 data-v-16884332=\"\"><strong>Die Halle der vier S\u00e4ulen<\/strong><\/h4>\n<div class=\"q-img q-img--menu article-image\" role=\"img\" data-v-16884332=\"\">\n<div><\/div>\n<div class=\"q-img__container absolute-full\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-13157\" src=\"https:\/\/legendnilecruise.com\/wp-content\/uploads\/2025\/03\/hall-300x197.png\" alt=\"\" width=\"1089\" height=\"715\" srcset=\"https:\/\/legendnilecruise.com\/wp-content\/uploads\/2025\/03\/hall-300x197.png 300w, https:\/\/legendnilecruise.com\/wp-content\/uploads\/2025\/03\/hall-768x504.png 768w, https:\/\/legendnilecruise.com\/wp-content\/uploads\/2025\/03\/hall-686x450.png 686w, https:\/\/legendnilecruise.com\/wp-content\/uploads\/2025\/03\/hall.png 825w\" sizes=\"(max-width: 1089px) 100vw, 1089px\" \/><\/div>\n<div class=\"q-img__content absolute-full q-anchor--skip\"><\/div>\n<\/div>\n<\/div>\n<div class=\"article-part\" data-v-16884332=\"\">\n<h4 data-v-16884332=\"\"><strong>einer der Pfeiler in der Vier-S\u00e4ulen-Halle<\/strong><\/h4>\n<div class=\"q-img q-img--menu article-image\" role=\"img\" data-v-16884332=\"\">\n<div><\/div>\n<div class=\"q-img__container absolute-full\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-13156\" src=\"https:\/\/legendnilecruise.com\/wp-content\/uploads\/2025\/03\/one.jpg\" alt=\"\" width=\"948\" height=\"856\" \/><\/div>\n<div class=\"q-img__content absolute-full q-anchor--skip\"><\/div>\n<\/div>\n<\/div>\n<div class=\"article-part\" data-v-16884332=\"\">\n<h4 data-v-16884332=\"\"><strong>Eine kleine Kammer vor der Grabkammer<\/strong><\/h4>\n<p data-v-16884332=\"\">Wir finden Szenen, die den K\u00f6nig vor den G\u00f6ttern der Magie zeigen. Dann betet er vor zwei Wasserbecken und einigen Pavianen (ein Symbol des Gottes Thoth) an und verehrt anschlie\u00dfend Maat (die G\u00f6ttin der Gerechtigkeit). An der Decke ist die Auferstehung des Osiris dargestellt. K\u00f6nig bei der Anbetung des Gottes Osiris<\/p>\n<\/div>\n<div class=\"article-part\" data-v-16884332=\"\">\n<h4 data-v-16884332=\"\"><strong>Ansicht des K\u00f6nigs bei der Anbetung des Gottes Osiris<\/strong><\/h4>\n<div class=\"q-img q-img--menu article-image\" role=\"img\" data-v-16884332=\"\">\n<div><\/div>\n<div class=\"q-img__container absolute-full\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-13155\" src=\"https:\/\/legendnilecruise.com\/wp-content\/uploads\/2025\/03\/view-225x300.jpg\" alt=\"\" width=\"1000\" height=\"1333\" srcset=\"https:\/\/legendnilecruise.com\/wp-content\/uploads\/2025\/03\/view-225x300.jpg 225w, https:\/\/legendnilecruise.com\/wp-content\/uploads\/2025\/03\/view.jpg 300w\" sizes=\"(max-width: 1000px) 100vw, 1000px\" \/><\/div>\n<div class=\"q-img__content absolute-full q-anchor--skip\"><\/div>\n<\/div>\n<\/div>\n<div class=\"article-part\" data-v-16884332=\"\">\n<h4 data-v-16884332=\"\"><strong>Die Grabkammer<\/strong><\/h4>\n<p data-v-16884332=\"\">Es hat vier S\u00e4ulen, in deren Mitte sich der Granitsarkophag befindet. Auf den S\u00e4ulen sind Szenen des K\u00f6nigs mit den G\u00f6ttern zu sehen, und wir bemerken die himmlische Decke mit dem Buch der Nacht und des Tages. Rechts an den W\u00e4nden sehen wir Szenen aus dem Buch der Erde (Aker) mit der ber\u00fchmten Szene, die einen liegenden L\u00f6wen mit zwei K\u00f6pfen darstellt, die in entgegengesetzte Richtungen weisen, wobei der Westen das Gestern und der Osten das Heute repr\u00e4sentiert. Und aus der Mitte taucht ein Arm des Gottes Nun auf, um die Sonnenscheibe zu empfangen, in deren Zentrum Khepri mit einem Widderkopf steht, und zwei R\u00f6cke in Form von Alba-V\u00f6geln und menschlichen K\u00f6pfen beten ihn an. Wir sehen, dass das Boot der Sonne von sieben Alba-V\u00f6geln mit menschlichen K\u00f6pfen gezogen wird. Und wir sehen den Gott Tatenen, der auf die Urerde zeigt, um das Sonnenboot aufzunehmen. Und wir bemerken den Gott Nun, der die Sonnenscheibe anhebt (vier Kobraschlangen mit menschlichen K\u00f6pfen und menschlichen Armen ziehen die Sonnenscheibe). Auf der linken Seite und im Inneren der Sarkophagkammer erscheinen Isis und Nephthys auf der rechten Seite. Und rechts und links des Flusses erscheinen zwei kleine Boote, und der Fluss beginnt nach Westen zu flie\u00dfen, und an jedem Ufer stehen zwei Schakale, Geister des Westens in goldener Farbe, dann erscheint eine Prozession mit vielen Figuren, die alle den verstorbenen K\u00f6nig darstellen, und im Inneren der Sarkophagkammer erscheinen Schakale am Anfang der vierten und f\u00fcnften Reihe mit einer Prozession von Figuren, die dem K\u00f6nig in der unteren Reihe geh\u00f6ren.<\/p>\n<\/div>\n<h4 data-v-16884332=\"\"><strong>Die kleine Kammer im Inneren der Grabkammer<\/strong><\/h4>\n<p class=\"article-part\">An der R\u00fcckwand befindet sich eine Ansicht des zw\u00f6lften <strong>Kapitel<\/strong> des Buches der Tore (Gott Nun hebt das Sonnenboot).<\/p>\n<div class=\"article-part\" data-v-16884332=\"\">\n<h4 data-v-16884332=\"\"><strong>Grabkammer mit dem Sarkophag des K\u00f6nigs<\/strong><\/h4>\n<div class=\"q-img q-img--menu article-image\" role=\"img\" data-v-16884332=\"\">\n<div><\/div>\n<div class=\"q-img__container absolute-full\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-13154\" src=\"https:\/\/legendnilecruise.com\/wp-content\/uploads\/2025\/03\/burial-300x199.png\" alt=\"\" width=\"1063\" height=\"705\" srcset=\"https:\/\/legendnilecruise.com\/wp-content\/uploads\/2025\/03\/burial-300x199.png 300w, https:\/\/legendnilecruise.com\/wp-content\/uploads\/2025\/03\/burial-768x510.png 768w, https:\/\/legendnilecruise.com\/wp-content\/uploads\/2025\/03\/burial-677x450.png 677w, https:\/\/legendnilecruise.com\/wp-content\/uploads\/2025\/03\/burial.png 841w\" sizes=\"(max-width: 1063px) 100vw, 1063px\" \/><\/div>\n<div class=\"q-img__content absolute-full q-anchor--skip\"><\/div>\n<\/div>\n<\/div>\n<div class=\"article-part\" data-v-16884332=\"\">\n<h4 data-v-16884332=\"\"><strong>Szene aus dem Buch der Erde, die einen L\u00f6wen mit zwei menschlichen K\u00f6pfen zeigt<\/strong><\/h4>\n<div class=\"q-img q-img--menu article-image\" role=\"img\" data-v-16884332=\"\">\n<div><\/div>\n<div class=\"q-img__container absolute-full\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-13153\" src=\"https:\/\/legendnilecruise.com\/wp-content\/uploads\/2025\/03\/book_W5mo2Av-300x225.jpg\" alt=\"\" width=\"975\" height=\"731\" srcset=\"https:\/\/legendnilecruise.com\/wp-content\/uploads\/2025\/03\/book_W5mo2Av-300x225.jpg 300w, https:\/\/legendnilecruise.com\/wp-content\/uploads\/2025\/03\/book_W5mo2Av.jpg 400w\" sizes=\"(max-width: 975px) 100vw, 975px\" \/><\/div>\n<div class=\"q-img__content absolute-full q-anchor--skip\"><\/div>\n<\/div>\n<\/div>\n<div class=\"article-part\" data-v-16884332=\"\">\n<h4 data-v-16884332=\"\"><strong>Die G\u00f6ttin Nut, die G\u00f6ttin des Himmels, und in ihr sind Boote, die von G\u00f6ttern im Jenseits gezogen werden<\/strong><\/h4>\n<div class=\"q-img q-img--menu article-image\" role=\"img\" data-v-16884332=\"\">\n<div><\/div>\n<div class=\"q-img__container absolute-full\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-13152\" src=\"https:\/\/legendnilecruise.com\/wp-content\/uploads\/2025\/03\/nut-300x174.png\" alt=\"\" width=\"1012\" height=\"587\" srcset=\"https:\/\/legendnilecruise.com\/wp-content\/uploads\/2025\/03\/nut-300x174.png 300w, https:\/\/legendnilecruise.com\/wp-content\/uploads\/2025\/03\/nut.png 588w\" sizes=\"(max-width: 1012px) 100vw, 1012px\" \/><\/div>\n<div class=\"q-img__content absolute-full q-anchor--skip\"><\/div>\n<\/div>\n<\/div>\n<div class=\"article-part\" data-v-16884332=\"\">\n<h4 data-v-16884332=\"\"><strong>Die S\u00fcdwand der Grabkammer<\/strong><\/h4>\n<div class=\"q-img q-img--menu article-image\" role=\"img\" data-v-16884332=\"\">\n<div><\/div>\n<div class=\"q-img__container absolute-full\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-13151\" src=\"https:\/\/legendnilecruise.com\/wp-content\/uploads\/2025\/03\/wall-300x200.png\" alt=\"\" width=\"1088\" height=\"725\" srcset=\"https:\/\/legendnilecruise.com\/wp-content\/uploads\/2025\/03\/wall-300x200.png 300w, https:\/\/legendnilecruise.com\/wp-content\/uploads\/2025\/03\/wall-768x512.png 768w, https:\/\/legendnilecruise.com\/wp-content\/uploads\/2025\/03\/wall-675x450.png 675w, https:\/\/legendnilecruise.com\/wp-content\/uploads\/2025\/03\/wall.png 776w\" sizes=\"(max-width: 1088px) 100vw, 1088px\" \/><\/div>\n<div class=\"q-img__content absolute-full q-anchor--skip\"><\/div>\n<\/div>\n<\/div>\n<div class=\"article-part\" data-v-16884332=\"\">\n<h4 data-v-16884332=\"\"><strong>Die Nordwand der Grabkammer 1<\/strong><\/h4>\n<div class=\"q-img q-img--menu article-image\" role=\"img\" data-v-16884332=\"\">\n<div><\/div>\n<div class=\"q-img__container absolute-full\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-13150\" src=\"https:\/\/legendnilecruise.com\/wp-content\/uploads\/2025\/03\/wc1-300x200.png\" alt=\"\" width=\"1088\" height=\"725\" srcset=\"https:\/\/legendnilecruise.com\/wp-content\/uploads\/2025\/03\/wc1-300x200.png 300w, https:\/\/legendnilecruise.com\/wp-content\/uploads\/2025\/03\/wc1-768x513.png 768w, https:\/\/legendnilecruise.com\/wp-content\/uploads\/2025\/03\/wc1-674x450.png 674w, https:\/\/legendnilecruise.com\/wp-content\/uploads\/2025\/03\/wc1.png 800w\" sizes=\"(max-width: 1088px) 100vw, 1088px\" \/><\/div>\n<div class=\"q-img__content absolute-full q-anchor--skip\"><\/div>\n<\/div>\n<\/div>\n<div class=\"article-part\" data-v-16884332=\"\">\n<h4 data-v-16884332=\"\"><strong>Die Nordwand der Grabkammer 2<\/strong><\/h4>\n<div class=\"q-img q-img--menu article-image\" role=\"img\" data-v-16884332=\"\">\n<div><\/div>\n<div class=\"q-img__container absolute-full\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-13149\" src=\"https:\/\/legendnilecruise.com\/wp-content\/uploads\/2025\/03\/wc2-300x200.jpg\" alt=\"\" width=\"983\" height=\"655\" srcset=\"https:\/\/legendnilecruise.com\/wp-content\/uploads\/2025\/03\/wc2-300x200.jpg 300w, https:\/\/legendnilecruise.com\/wp-content\/uploads\/2025\/03\/wc2-1024x683.jpg 1024w, https:\/\/legendnilecruise.com\/wp-content\/uploads\/2025\/03\/wc2-768x512.jpg 768w, https:\/\/legendnilecruise.com\/wp-content\/uploads\/2025\/03\/wc2-675x450.jpg 675w, https:\/\/legendnilecruise.com\/wp-content\/uploads\/2025\/03\/wc2.jpg 1059w\" sizes=\"(max-width: 983px) 100vw, 983px\" \/><\/div>\n<div class=\"q-img__content absolute-full q-anchor--skip\"><\/div>\n<\/div>\n<\/div>\n<div class=\"article-part\" data-v-16884332=\"\">\n<h4 data-v-16884332=\"\"><strong>K\u00f6nig Seti I.<\/strong><\/h4>\n<p data-v-16884332=\"\">K\u00f6nig Seti I., der Sohn von Ramses I., dem Gr\u00fcnder der 19. Dynastie, regierte \u00c4gypten mindestens einundzwanzig Jahre lang. Nachdem er K\u00f6nig geworden war, f\u00fchrte er verschiedene Feldz\u00fcge in Libyen und Syrien durch, um die \u00e4gyptische Kontrolle im Ausland wiederherzustellen. K\u00f6nig Seti I. war der erste \u00e4gyptische K\u00f6nig, der gegen die Hethiter, die neue Supermacht im Nahen Osten, k\u00e4mpfte. Diese Aktivit\u00e4ten und milit\u00e4rischen Siege wurden mit gro\u00dfem Geschick auf der Kolonnade festgehalten, die im Amun-Tempel in Karnak zu entstehen begann. K\u00f6nig Seti I. ordnete die Durchf\u00fchrung zahlreicher gro\u00dfer Bauprojekte an, sowohl in Karnak als auch in Abydos, und er baute auch einen Totentempel am Westufer von Theben. W\u00e4hrend seiner Regierungszeit begann man, in gro\u00dfem Umfang Schlachtszenen an den W\u00e4nden der \u00e4gyptischen Tempel darzustellen, um politische Propaganda zu betreiben und die Macht des K\u00f6nigs zu verk\u00fcnden. Der Regierungszeit des K\u00f6nigs wird auch die \u00e4lteste geologische Karte der Welt mit Goldminen zugeschrieben, die auf einem Papyrus aufgezeichnet ist, der heute im Turiner Museum in Italien aufbewahrt wird. Das Grab von K\u00f6nig Seti I. im Tal der K\u00f6nige (KV 17) ist eines der sch\u00f6nsten K\u00f6nigsgr\u00e4ber, da seine Wandszenen ihre leuchtenden Farben bewahrt haben, einschlie\u00dflich der dunkelblauen Farbe, die den Nachthimmel imitiert und an einigen Decken zu sehen ist.<\/p>\n<\/div>\n<div class=\"article-part\" data-v-16884332=\"\">\n<h4 data-v-16884332=\"\"><strong>K\u00f6nig Seti I. zwischen den G\u00f6ttern Horus und Osiris<\/strong><\/h4>\n<div class=\"q-img q-img--menu article-image\" role=\"img\" data-v-16884332=\"\">\n<div><\/div>\n<div class=\"q-img__container absolute-full\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-13148\" src=\"https:\/\/legendnilecruise.com\/wp-content\/uploads\/2025\/03\/seti-300x176.png\" alt=\"\" width=\"1086\" height=\"637\" srcset=\"https:\/\/legendnilecruise.com\/wp-content\/uploads\/2025\/03\/seti-300x176.png 300w, https:\/\/legendnilecruise.com\/wp-content\/uploads\/2025\/03\/seti.png 706w\" sizes=\"(max-width: 1086px) 100vw, 1086px\" \/><\/div>\n<div class=\"q-img__content absolute-full q-anchor--skip\"><\/div>\n<\/div>\n<\/div>\n<div class=\"article-part\" data-v-16884332=\"\">\n<h4 data-v-16884332=\"\"><strong>Eingang zum Grabmal von Seti I.<\/strong><\/h4>\n<div class=\"q-img q-img--menu article-image\" role=\"img\" data-v-16884332=\"\">\n<div><\/div>\n<div class=\"q-img__container absolute-full\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-13147\" src=\"https:\/\/legendnilecruise.com\/wp-content\/uploads\/2025\/03\/seti_l-225x300.jpg\" alt=\"\" width=\"1084\" height=\"1445\" srcset=\"https:\/\/legendnilecruise.com\/wp-content\/uploads\/2025\/03\/seti_l-225x300.jpg 225w, https:\/\/legendnilecruise.com\/wp-content\/uploads\/2025\/03\/seti_l.jpg 300w\" sizes=\"(max-width: 1084px) 100vw, 1084px\" \/><\/div>\n<div class=\"q-img__content absolute-full q-anchor--skip\"><\/div>\n<\/div>\n<\/div>\n<div class=\"article-part\" data-v-16884332=\"\">\n<h4 data-v-16884332=\"\"><strong>Das Grabmal von Seti I. (KV 17)<\/strong><\/h4>\n<p data-v-16884332=\"\">wurde 1817 von Belzoni entdeckt und daher Belzonis Grab genannt. Seine Tiefe betr\u00e4gt 98 Meter.<\/p>\n<\/div>\n<div class=\"article-part\" data-v-16884332=\"\">\n<h4 data-v-16884332=\"\"><strong>Beschreibung des Grabes<\/strong><\/h4>\n<p data-v-16884332=\"\">Korridore Auf der rechten Seite sind Hymnen zu sehen, die Ra preisen. Auf der linken Seite befindet sich eine Szene der solaren Triade (Khepri-Ra-Atum). Dann erreichen wir eine absteigende Treppe, auf deren beiden Seiten sich \u00d6ffnungen im Fels befinden, wo wir rechts und links Szenen von D\u00e4monen mit ihren Namen sehen, dann Hymnen, die Ra preisen. Dann sehen wir Szenen von Nephthys und Isis kniend, eine der Szenen der vierten Stunde des Buches Amduat (das, was im Jenseits ist). Im dritten Korridor befindet sich rechts die vierte Stunde und links die f\u00fcnfte Stunde des Buches Amduat. Dann erreichen wir die Brunnenkammer.<\/p>\n<\/div>\n<div class=\"article-part\" data-v-16884332=\"\">\n<h4 data-v-16884332=\"\"><strong>Bild aus dem Buch der Tore, das an den W\u00e4nden des Grabes angebracht ist<\/strong><\/h4>\n<div class=\"q-img q-img--menu article-image\" role=\"img\" data-v-16884332=\"\">\n<div><\/div>\n<div class=\"q-img__container absolute-full\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-13146\" src=\"https:\/\/legendnilecruise.com\/wp-content\/uploads\/2025\/03\/gates-300x177.png\" alt=\"\" width=\"1085\" height=\"640\" srcset=\"https:\/\/legendnilecruise.com\/wp-content\/uploads\/2025\/03\/gates-300x177.png 300w, https:\/\/legendnilecruise.com\/wp-content\/uploads\/2025\/03\/gates-768x454.png 768w, https:\/\/legendnilecruise.com\/wp-content\/uploads\/2025\/03\/gates-761x450.png 761w, https:\/\/legendnilecruise.com\/wp-content\/uploads\/2025\/03\/gates.png 844w\" sizes=\"(max-width: 1085px) 100vw, 1085px\" \/><\/div>\n<div class=\"q-img__loading absolute-full flex flex-center\"><\/div>\n<\/div>\n<\/div>\n<div class=\"article-part\" data-v-16884332=\"\">\n<h4 data-v-16884332=\"\"><strong>Einzelheiten aus der zweiten Stunde des Buches Amduat<\/strong><\/h4>\n<div class=\"q-img q-img--menu article-image\" role=\"img\" data-v-16884332=\"\">\n<div><\/div>\n<div class=\"q-img__container absolute-full\"><\/div>\n<div class=\"q-img__loading absolute-full flex flex-center\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-13145\" src=\"https:\/\/legendnilecruise.com\/wp-content\/uploads\/2025\/03\/hour.jpg\" alt=\"\" width=\"1086\" height=\"761\" \/><\/div>\n<\/div>\n<\/div>\n<div class=\"article-part\" data-v-16884332=\"\">\n<h4 data-v-16884332=\"\"><strong>Einzelheiten aus der zweiten Stunde des Buches Amduat<\/strong><\/h4>\n<div class=\"q-img q-img--menu article-image\" role=\"img\" data-v-16884332=\"\">\n<div><\/div>\n<div class=\"q-img__container absolute-full\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-13144\" src=\"https:\/\/legendnilecruise.com\/wp-content\/uploads\/2025\/03\/second_book.jpg\" alt=\"\" width=\"1087\" height=\"750\" \/><\/div>\n<div class=\"q-img__loading absolute-full flex flex-center\"><\/div>\n<\/div>\n<\/div>\n<div class=\"article-part\" data-v-16884332=\"\">\n<h4 data-v-16884332=\"\"><strong>Einzelheiten aus der vierten Stunde des Buches Amduat<\/strong><\/h4>\n<div class=\"q-img q-img--menu article-image\" role=\"img\" data-v-16884332=\"\">\n<div><\/div>\n<div class=\"q-img__container absolute-full\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-13143\" src=\"https:\/\/legendnilecruise.com\/wp-content\/uploads\/2025\/03\/detials-300x233.jpg\" alt=\"\" width=\"944\" height=\"733\" srcset=\"https:\/\/legendnilecruise.com\/wp-content\/uploads\/2025\/03\/detials-300x233.jpg 300w, https:\/\/legendnilecruise.com\/wp-content\/uploads\/2025\/03\/detials.jpg 311w\" sizes=\"(max-width: 944px) 100vw, 944px\" \/><\/div>\n<div class=\"q-img__loading absolute-full flex flex-center\"><\/div>\n<\/div>\n<\/div>\n<div class=\"article-part\" data-v-16884332=\"\">\n<h4 data-v-16884332=\"\"><strong>Die Brunnenkammer<\/strong><\/h4>\n<p data-v-16884332=\"\">Es zeichnet sich durch sehr sch\u00f6ne Szenen aus, in denen wir den K\u00f6nig bei der Anbetung verschiedener G\u00f6tter sehen.<\/p>\n<\/div>\n<div class=\"article-part\" data-v-16884332=\"\">\n<h4 data-v-16884332=\"\"><strong>S\u00e4ulen Hallen<\/strong><\/h4>\n<p data-v-16884332=\"\">Dann betreten wir einen Saal mit vier S\u00e4ulen, wo wir links eine Szene aus dem Buch der Tore finden, die die vier den alten \u00c4gyptern bekannten menschlichen Formen (\u00e4gyptisch, asiatisch, nubisch, libysch) darstellt. Dann gelangen wir in einen Saal mit zwei S\u00e4ulen, an dessen W\u00e4nden in roter Farbe Szenen aus dem Buch Amduat dargestellt sind, aber die Inschrift wurde nicht vollendet. Auf den beiden S\u00e4ulen sind Szenen des K\u00f6nigs mit verschiedenen G\u00f6ttern dargestellt<\/p>\n<\/div>\n<div class=\"article-part\" data-v-16884332=\"\">\n<h4 data-v-16884332=\"\"><strong>K\u00f6nig mit dem Gott Osiris<\/strong><\/h4>\n<div class=\"q-img q-img--menu article-image\" role=\"img\" data-v-16884332=\"\">\n<div><\/div>\n<div class=\"q-img__container absolute-full\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-13142\" src=\"https:\/\/legendnilecruise.com\/wp-content\/uploads\/2025\/03\/osirirs-270x300.jpg\" alt=\"\" width=\"1062\" height=\"1180\" srcset=\"https:\/\/legendnilecruise.com\/wp-content\/uploads\/2025\/03\/osirirs-270x300.jpg 270w, https:\/\/legendnilecruise.com\/wp-content\/uploads\/2025\/03\/osirirs.jpg 313w\" sizes=\"(max-width: 1062px) 100vw, 1062px\" \/><\/div>\n<div class=\"q-img__loading absolute-full flex flex-center\"><\/div>\n<\/div>\n<\/div>\n<div class=\"article-part\" data-v-16884332=\"\">\n<h4 data-v-16884332=\"\"><strong>K\u00f6nig mit dem Gott Thoth<\/strong><\/h4>\n<div class=\"q-img q-img--menu article-image\" role=\"img\" data-v-16884332=\"\">\n<div><\/div>\n<div class=\"q-img__container absolute-full\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-13141\" src=\"https:\/\/legendnilecruise.com\/wp-content\/uploads\/2025\/03\/thoth-269x300.jpg\" alt=\"\" width=\"1087\" height=\"1212\" srcset=\"https:\/\/legendnilecruise.com\/wp-content\/uploads\/2025\/03\/thoth-269x300.jpg 269w, https:\/\/legendnilecruise.com\/wp-content\/uploads\/2025\/03\/thoth.jpg 325w\" sizes=\"(max-width: 1087px) 100vw, 1087px\" \/><\/div>\n<div class=\"q-img__loading absolute-full flex flex-center\"><\/div>\n<\/div>\n<\/div>\n<div class=\"article-part\" data-v-16884332=\"\">\n<h4 data-v-16884332=\"\"><strong>Der Korridor<\/strong><\/h4>\n<p data-v-16884332=\"\">Wir kehren in die Halle mit den vier S\u00e4ulen zur\u00fcck und steigen von dort in einen Korridor hinab, wo wir rechts und links \u00e4hnliche Szenen der Opferliste sehen, dann Hymnen, die das Auge des Horus preisen, und wir bemerken das ber\u00fchmte Ritual des \u00d6ffnens des Mundes.<\/p>\n<\/div>\n<div class=\"article-part\" data-v-16884332=\"\">\n<h4 data-v-16884332=\"\"><strong>Korridor vor der Grabkammer<\/strong><\/h4>\n<div class=\"q-img q-img--menu article-image\" role=\"img\" data-v-16884332=\"\">\n<div><\/div>\n<div class=\"q-img__container absolute-full\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-13140\" src=\"https:\/\/legendnilecruise.com\/wp-content\/uploads\/2025\/03\/corri-225x300.jpg\" alt=\"\" width=\"1086\" height=\"1448\" srcset=\"https:\/\/legendnilecruise.com\/wp-content\/uploads\/2025\/03\/corri-225x300.jpg 225w, https:\/\/legendnilecruise.com\/wp-content\/uploads\/2025\/03\/corri.jpg 300w\" sizes=\"(max-width: 1086px) 100vw, 1086px\" \/><\/div>\n<div class=\"q-img__loading absolute-full flex flex-center\"><\/div>\n<\/div>\n<\/div>\n<div class=\"article-part\" data-v-16884332=\"\">\n<h4 data-v-16884332=\"\"><strong>Die Grabkammer<\/strong><\/h4>\n<p data-v-16884332=\"\">Es besteht aus einem vorderen Teil und einem hinteren Teil. Der vordere Teil Eine rechteckige Kammer mit 6 S\u00e4ulen in zwei Reihen. Die erste Reihe von vier S\u00e4ulen stellt Szenen des K\u00f6nigs mit verschiedenen G\u00f6ttern dar. Auf den beiden hinteren S\u00e4ulen sind die Geister der Stadt Buto mit dem Kopf eines Falken auf der linken Seite zu sehen. Auf der rechten Seite befinden sich die Geister der Stadt Nekhen mit dem Kopf eines Schakals. An den W\u00e4nden sind Szenen aus dem Buch der Tore zu sehen. Der hintere Teil ist die sch\u00f6nste der Szenen des Tals der K\u00f6nige, mit dem Sarkophag und der Decke in Form einer Kuppel, die den Himmel darstellt, und dar\u00fcber befindet sich eine Szene der G\u00f6ttin Nut, die ihren K\u00f6rper zur Erde beugt. Der Sarkophag wurde von Belzoni mitgenommen und befindet sich heute im British Museum in London. Die f\u00fcnf Kammern Eine Kammer mit vier S\u00e4ulen vor dem Sarkophag und zwei Kammern auf der rechten und zwei Kammern auf der linken Seite.<\/p>\n<\/div>\n<div class=\"article-part\" data-v-16884332=\"\">\n<h4 data-v-16884332=\"\"><strong>Die wichtigsten Szenen in den Kammern<\/strong><\/h4>\n<p data-v-16884332=\"\">In der ersten Kammer auf der rechten Seite, die Geschichte der Zerst\u00f6rung der Menschheit. Eine Szene von Hathor als Kuh mit den Sternen des Himmels, die von Shu angehoben werden, und dar\u00fcber schwimmt das Schiff von Ra.<\/p>\n<\/div>\n<div class=\"article-part\" data-v-16884332=\"\">\n<h4 data-v-16884332=\"\"><strong>G\u00f6ttin Hathor in Form einer Kuh aus dem Grab von Seti I.<\/strong><\/h4>\n<div class=\"q-img q-img--menu article-image\" role=\"img\" data-v-16884332=\"\">\n<div><\/div>\n<div class=\"q-img__container absolute-full\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-13139\" src=\"https:\/\/legendnilecruise.com\/wp-content\/uploads\/2025\/03\/Hathor-225x300.jpg\" alt=\"\" width=\"1086\" height=\"1448\" srcset=\"https:\/\/legendnilecruise.com\/wp-content\/uploads\/2025\/03\/Hathor-225x300.jpg 225w, https:\/\/legendnilecruise.com\/wp-content\/uploads\/2025\/03\/Hathor.jpg 260w\" sizes=\"(max-width: 1086px) 100vw, 1086px\" \/><\/div>\n<div class=\"q-img__loading absolute-full flex flex-center\"><\/div>\n<\/div>\n<\/div>\n<div class=\"article-part\" data-v-16884332=\"\">\n<h4 data-v-16884332=\"\"><strong>Details aus dem Buch von Amduat von den W\u00e4nden der Kammer neben der Grabkammer<\/strong><\/h4>\n<div class=\"q-img q-img--menu article-image\" role=\"img\" data-v-16884332=\"\">\n<div><\/div>\n<div class=\"q-img__container absolute-full\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-13138\" src=\"https:\/\/legendnilecruise.com\/wp-content\/uploads\/2025\/03\/bboook-300x189.png\" alt=\"\" width=\"1087\" height=\"685\" srcset=\"https:\/\/legendnilecruise.com\/wp-content\/uploads\/2025\/03\/bboook-300x189.png 300w, https:\/\/legendnilecruise.com\/wp-content\/uploads\/2025\/03\/bboook-715x450.png 715w, https:\/\/legendnilecruise.com\/wp-content\/uploads\/2025\/03\/bboook.png 729w\" sizes=\"(max-width: 1087px) 100vw, 1087px\" \/><\/div>\n<div class=\"q-img__loading absolute-full flex flex-center\"><\/div>\n<\/div>\n<\/div>\n<div class=\"gallery\" data-v-16884332=\"\">\n<div class=\"gallery-mask mask-off\" data-v-16884332=\"\">\n<div class=\"q-img q-img--menu mask-image\" role=\"img\" data-v-16884332=\"\" aria-label=\"Ausgew\u00e4hltes Bild\">\n<div><\/div>\n<div class=\"q-img__content absolute-full q-anchor--skip\"><\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/section>\n<\/article>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div id=\"q-notify\" data-v-app=\"\">\n<div class=\"q-notifications\">\n<div class=\"q-notifications__list q-notifications__list--top fixed column no-wrap items-start\"><\/div>\n<div class=\"q-notifications__list q-notifications__list--top fixed column no-wrap items-end\"><\/div>\n<div class=\"q-notifications__list q-notifications__list--bottom fixed column no-wrap items-start\"><\/div>\n<div class=\"q-notifications__list q-notifications__list--bottom fixed column no-wrap items-end\"><\/div>\n<div class=\"q-notifications__list q-notifications__list--top fixed column no-wrap items-center\"><\/div>\n<div class=\"q-notifications__list q-notifications__list--bottom fixed column no-wrap items-center\"><\/div>\n<\/div>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Eine wunderbare Gelassenheit hat von meiner ganzen Seele Besitz ergriffen, wie diese s\u00fc\u00dfen Fr\u00fchlingsmorgen, die ich mit ganzem Herzen genie\u00dfe. Ich bin allein und f\u00fchle den Zauber des Daseins an diesem Ort, der f\u00fcr die Gl\u00fcckseligkeit von Seelen wie der meinen geschaffen wurde. Ich bin so gl\u00fccklich, mein lieber Freund, so vertieft in [...]<\/p>","protected":false},"author":1,"featured_media":13218,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[136],"tags":[],"class_list":["post-13125","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-articles"],"_links":{"self":[{"href":"https:\/\/legendnilecruise.com\/de\/wp-json\/wp\/v2\/posts\/13125","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/legendnilecruise.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/legendnilecruise.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/legendnilecruise.com\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/legendnilecruise.com\/de\/wp-json\/wp\/v2\/comments?post=13125"}],"version-history":[{"count":3,"href":"https:\/\/legendnilecruise.com\/de\/wp-json\/wp\/v2\/posts\/13125\/revisions"}],"predecessor-version":[{"id":13215,"href":"https:\/\/legendnilecruise.com\/de\/wp-json\/wp\/v2\/posts\/13125\/revisions\/13215"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/legendnilecruise.com\/de\/wp-json\/wp\/v2\/media\/13218"}],"wp:attachment":[{"href":"https:\/\/legendnilecruise.com\/de\/wp-json\/wp\/v2\/media?parent=13125"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/legendnilecruise.com\/de\/wp-json\/wp\/v2\/categories?post=13125"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/legendnilecruise.com\/de\/wp-json\/wp\/v2\/tags?post=13125"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}