{"id":12429,"date":"2025-03-24T12:26:09","date_gmt":"2025-03-24T12:26:09","guid":{"rendered":"https:\/\/legendnilecruise.com\/?p=12429"},"modified":"2025-03-25T07:45:34","modified_gmt":"2025-03-25T07:45:34","slug":"king-thutmose-iii","status":"publish","type":"post","link":"https:\/\/legendnilecruise.com\/de\/konige-und-koniginnen\/konig-thutmose-iii\/","title":{"rendered":"K\u00f6nig Thutmose III."},"content":{"rendered":"<h2>K\u00f6nig Thutmose III. (Begr\u00fcnder des \u00e4gyptischen Reiches)<\/h2>\n<p>K\u00f6nig Thutmose III. gilt als der gr\u00f6\u00dfte K\u00f6nig des alten \u00c4gypten. Er dehnte das \u00e4gyptische Reich bis in die Mitte Afrikas und bis in die T\u00fcrkei in Asien aus. Thutmose III. sagte: \"Wir sind das Volk, das die Moral begr\u00fcndet hat\", was bedeutet, dass die gesamte \u00e4gyptische Zivilisation auf ethischen Grunds\u00e4tzen beruhte. Er regierte nach Hatschepsut und errichtete die meisten Bauwerke des Karnak-Tempels, insbesondere das Allerheiligste und den \"Akh meno\"-Tempel, der Teil des Amun-Ra-Tempels ist. Dort befindet sich eine Stele, die so genannte \"Ahnentafel\", eine der wichtigsten Quellen der alt\u00e4gyptischen Geschichte. Sie listet die Namen der K\u00f6nige vom Alten Reich bis zu Thutmose III. selbst auf (heute im Louvre-Museum in Paris). Thutmose III. hinterlie\u00df uns ein bemerkenswertes Verm\u00e4chtnis im \"Akh meno\"-Tempel, dem \u00e4ltesten Zoo der Welt. Hier sind Darstellungen aller Tiere zu sehen, die Thutmose III. von seinen Eroberungen in verschiedenen L\u00e4ndern mitbrachte. Einer seiner bedeutendsten Beitr\u00e4ge war seine Vorreiterrolle in der politischen und milit\u00e4rischen Strategie. Er brachte die F\u00fcrstens\u00f6hne aus den eroberten L\u00e4ndern nach \u00c4gypten, bildete sie aus und vermittelte ihnen ein Gef\u00fchl der Zugeh\u00f6rigkeit zur \u00e4gyptischen Zivilisation. Diese Politik wurde sp\u00e4ter im 19. Jahrhundert vom britischen Empire \u00fcbernommen. Was die milit\u00e4rische Taktik betrifft, so hatte Thutmose III. w\u00e4hrend der Schlacht von Megiddo die Wahl zwischen drei Routen, um die Stadt (in Syrien) zu erreichen. Zwei waren einfach, w\u00fcrden aber einen Monat dauern, w\u00e4hrend die dritte schwierig und schmal war, aber die Reise auf zehn Tage verk\u00fcrzen w\u00fcrde. Er w\u00e4hlte die schwierige Route, \u00fcberraschte seine Feinde und f\u00fcgte ihnen eine vernichtende Niederlage zu. Diese Strategie wurde sp\u00e4ter vom britischen General Allenby im Ersten Weltkrieg \u00fcbernommen und f\u00fchrte zu seinem Sieg \u00fcber die Franzosen. Thutmose III. war auch der erste, der seine Armee in drei Divisionen aufteilte: die mittlere, die rechte und die linke. Er lie\u00df das komplexeste Grabmal im Tal der K\u00f6nige errichten, das 1881 von dem franz\u00f6sischen Arch\u00e4ologen Victor Loret entdeckt wurde.<\/p>\n<p><img fetchpriority=\"high\" decoding=\"async\" class=\"alignnone wp-image-12431\" src=\"https:\/\/legendnilecruise.com\/wp-content\/uploads\/2025\/03\/King-Thutmose-III-1-199x300.png\" alt=\"K\u00f6nig Thutmose III.\" width=\"383\" height=\"577\" srcset=\"https:\/\/legendnilecruise.com\/wp-content\/uploads\/2025\/03\/King-Thutmose-III-1-199x300.png 199w, https:\/\/legendnilecruise.com\/wp-content\/uploads\/2025\/03\/King-Thutmose-III-1-299x450.png 299w, https:\/\/legendnilecruise.com\/wp-content\/uploads\/2025\/03\/King-Thutmose-III-1.png 363w\" sizes=\"(max-width: 383px) 100vw, 383px\" \/><\/p>","protected":false},"excerpt":{"rendered":"<p>K\u00f6nig Thutmose III. (Begr\u00fcnder des \u00e4gyptischen Reiches) K\u00f6nig Thutmose III. gilt als der gr\u00f6\u00dfte K\u00f6nig des alten \u00c4gypten. Er dehnte das \u00e4gyptische Reich bis in die Mitte Afrikas und bis in die T\u00fcrkei in Asien aus. Der ber\u00fchmte Ausspruch Thutmose III. \"Wir sind das Volk, das die Moral begr\u00fcndet hat\", bedeutet, dass die gesamte \u00e4gyptische Zivilisation [...]<\/p>","protected":false},"author":1,"featured_media":12432,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[72],"tags":[],"class_list":["post-12429","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-kings-and-queens"],"_links":{"self":[{"href":"https:\/\/legendnilecruise.com\/de\/wp-json\/wp\/v2\/posts\/12429","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/legendnilecruise.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/legendnilecruise.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/legendnilecruise.com\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/legendnilecruise.com\/de\/wp-json\/wp\/v2\/comments?post=12429"}],"version-history":[{"count":2,"href":"https:\/\/legendnilecruise.com\/de\/wp-json\/wp\/v2\/posts\/12429\/revisions"}],"predecessor-version":[{"id":12434,"href":"https:\/\/legendnilecruise.com\/de\/wp-json\/wp\/v2\/posts\/12429\/revisions\/12434"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/legendnilecruise.com\/de\/wp-json\/wp\/v2\/media\/12432"}],"wp:attachment":[{"href":"https:\/\/legendnilecruise.com\/de\/wp-json\/wp\/v2\/media?parent=12429"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/legendnilecruise.com\/de\/wp-json\/wp\/v2\/categories?post=12429"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/legendnilecruise.com\/de\/wp-json\/wp\/v2\/tags?post=12429"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}